{"id":24320,"date":"2016-07-07T11:16:55","date_gmt":"2016-07-07T11:16:55","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2016\/07\/07\/en-revolucion-asalto-y-robo-a-aeromexico\/"},"modified":"2016-07-07T11:16:55","modified_gmt":"2016-07-07T11:16:55","slug":"en-revolucion-asalto-y-robo-a-aeromexico","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/en-revolucion-asalto-y-robo-a-aeromexico\/","title":{"rendered":"EN REVOLUCI\u00d3N ASALTO Y ROBO A AEROM\u00c9XICO"},"content":{"rendered":"<p style=\"text-align: justify;\">DE PACHUCA<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Aunque inicialmente se dijo que dos sujetos con armas de fuego perpetraron un asalto y robo en las instalaciones de Aerom\u00e9xico que se ubica en la avenida Revoluci\u00f3n de esta capital hidalguense, posteriormente se refiri\u00f3 que son tres los implicados.<br \/>Secretar\u00eda de Seguridad Tr\u00e1nsito y Vialidad Municipal dijo que al lugar arribaron dos sujetos con armas de fuego, amagaron a los empleados\u00a0 para despojarlos de dinero en efectivo, sin que hasta el momento se especifique el monto.<br \/>Los informes iniciales refieren que el amargo incidente ocurri\u00f3 alrededor de las 9 de la ma\u00f1ana de ayer por ello efectivos de la Polic\u00eda Municipal de Pachuca implementaron un dispositivo para tratar de asegurar a los autores del asalto y robo, sin que hasta el momento se d\u00e9 la localizaci\u00f3n de los probables responsables.<br \/>Personal de la Agencia de Viajes de AeroM\u00e9xico que se encuentra muy cerca del centro comercial de Plaza Bella, record\u00f3 que los asaltantes llegaron y con pistola en mano sometieron a los empleados y los obligaron a que les entregar\u00e1n el dinero en efectivo.<br \/>Al lugar arrib\u00f3 Edwin Hern\u00e1ndez Garrido, Secretario de Seguridad P\u00fablica y Protecci\u00f3n Civil Municipal de Pachuca, quien se\u00f1al\u00f3 que se cuenta con un video, por lo que se analizan las caracter\u00edsticas de los autores y esperan que las pr\u00f3ximas horas se logren resultados positivos en la investigaci\u00f3n del caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DE PACHUCA<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-24320","post","type-post","status-publish","format-standard","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/24320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=24320"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/24320\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=24320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=24320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=24320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}