{"id":237767,"date":"2022-11-10T11:07:46","date_gmt":"2022-11-10T17:07:46","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=237767"},"modified":"2022-11-10T11:07:51","modified_gmt":"2022-11-10T17:07:51","slug":"rusia-se-retira-de-la-anexionada-ciudad-ucraniana-de-jerson","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/rusia-se-retira-de-la-anexionada-ciudad-ucraniana-de-jerson\/","title":{"rendered":"Rusia se retira de la anexionada ciudad ucraniana de Jers\u00f3n"},"content":{"rendered":"\n<p>(EFE).- El Ej\u00e9rcito ruso anunci\u00f3 su retirada de la anexionada ciudad ucraniana de Jers\u00f3n, la \u00fanica capital regional bajo control ruso en todo el pa\u00eds.<\/p>\n\n\n\n<p>&#8220;Proceda a la retirada de las tropas y adopte todas las medidas necesarias para garantizar el traslado seguro de las tropas, del armamento y de los equipos al otro lado del r\u00edo Dni\u00e9per&#8221;, orden\u00f3 el ministro ruso de Defensa, Sergu\u00e9i Shoig\u00fa, al jefe de la agrupaci\u00f3n de fuerzas rusas que combaten en Ucrania, general Sergu\u00e9i Surovikin.<\/p>\n\n\n\n<p>Shoig\u00fa aprob\u00f3 el repliegue despu\u00e9s de que Surovikin admitiera en su informe que la defensa de la ciudad y sus aleda\u00f1os en la orilla derecha del Dni\u00e9per es &#8220;inviable&#8221;.<\/p>\n\n\n\n<p>El general subray\u00f3 que en las condiciones actuales tampoco es posible abastecer al contingente militar ruso desplegado en la zona.<\/p>\n\n\n\n<p>Surovikin, que asumi\u00f3 a principios de octubre el mando de todas las tropas rusas en Ucrania, acus\u00f3 al Ej\u00e9rcito enemigo de bombardear objetivos civiles, desde escuelas a hospitales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EFE).- El Ej\u00e9rcito ruso anunci\u00f3 su retirada de la anexionada ciudad ucraniana de Jers\u00f3n, la \u00fanica capital regional bajo control ruso en todo el pa\u00eds. &#8220;Proceda a la retirada de las tropas y adopte todas las medidas necesarias para garantizar el traslado seguro de las tropas, del armamento y de los equipos al otro lado [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":237768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-237767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/237767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=237767"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/237767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/237768"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=237767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=237767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=237767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}