{"id":233752,"date":"2022-10-13T11:59:40","date_gmt":"2022-10-13T16:59:40","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=233752"},"modified":"2022-10-13T11:59:46","modified_gmt":"2022-10-13T16:59:46","slug":"latinoamerica-ahorraria-4-de-pib-si-entregara-ayuda-solo-a-necesitados","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/latinoamerica-ahorraria-4-de-pib-si-entregara-ayuda-solo-a-necesitados\/","title":{"rendered":"\u201cLatinoam\u00e9rica ahorrar\u00eda 4% de PIB si entregara ayuda solo a necesitados\u201d"},"content":{"rendered":"\n<p>(EFE).- La regi\u00f3n latinoamericana podr\u00eda ahorrar el 4 % de su Producto Interior Bruto (PIB) si realmente controlara que las ayudas se entregan solo a quien las necesita, apunt\u00f3 este mi\u00e9rcoles la presidenta del Banco Interamericano de Desarrollo (BID), Reina Irene Mej\u00eda.<\/p>\n\n\n\n<p>&#8220;La regi\u00f3n puede ahorrar un 4% del PIB asegurando que las transferencias solo se entreguen a quienes realmente las necesitan y, entre otras cosas, eliminando los sobreprecios en las compras&#8221;, apunt\u00f3 la presidenta en la inauguraci\u00f3n de la 56\u00aa Reuni\u00f3n de la Red de Bancos Centrales y Ministerios de Hacienda de Am\u00e9rica Latina y el Caribe.<\/p>\n\n\n\n<p>En los tiempos que corren, con una inflaci\u00f3n desbocada, los pol\u00edticos han tratado de mitigar sus impactos &#8220;a trav\u00e9s de transferencias y subsidios&#8221;, por eso hoy en d\u00eda deben ser &#8220;m\u00e1s eficientes&#8221; que nunca con el gasto p\u00fablico y garantizar que las ayudas van a quien realmente las necesita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EFE).- La regi\u00f3n latinoamericana podr\u00eda ahorrar el 4 % de su Producto Interior Bruto (PIB) si realmente controlara que las ayudas se entregan solo a quien las necesita, apunt\u00f3 este mi\u00e9rcoles la presidenta del Banco Interamericano de Desarrollo (BID), Reina Irene Mej\u00eda. &#8220;La regi\u00f3n puede ahorrar un 4% del PIB asegurando que las transferencias solo [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":233754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-233752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/233752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=233752"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/233752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/233754"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=233752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=233752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=233752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}