{"id":227944,"date":"2022-08-30T09:30:00","date_gmt":"2022-08-30T14:30:00","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=227944"},"modified":"2022-08-30T12:33:04","modified_gmt":"2022-08-30T17:33:04","slug":"esto-exige-el-dt-del-feyenoord-al-bebote","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/esto-exige-el-dt-del-feyenoord-al-bebote\/","title":{"rendered":"Esto exige el DT del Feyenoord al &#8220;Bebote&#8221;"},"content":{"rendered":"\n<p>Apenas van unas semanas que debut\u00f3 Santiago Gim\u00e9nez con el Feyenoord en la Eredivisie.<\/p>\n\n\n\n<p>El &#8220;Bebote&#8221; incluso ya marc\u00f3 un gol y dio una asistencia, en el juego m\u00e1s reciente ante el Emmen, donde los de Rotterdam ganaron en casa 4-0.<\/p>\n\n\n\n<p>Pero hay un detalle que inquieta al entrenador Arne Slot, y es que en declaraciones en conferencia de prensa explic\u00f3 qu\u00e9 le hace falta a Santi para poder ser titular con su equipo.<\/p>\n\n\n\n<p>&#8220;En la fase en la que entr\u00f3 Santiago Gim\u00e9nez no presionamos bien. \u00c9l tendr\u00e1 que ponerse fuerte f\u00edsicamente para poder manejar nuestro juego durante los 90 minutos&#8221;, asegur\u00f3 el director t\u00e9cnico.<\/p>\n\n\n\n<p>Gim\u00e9nez dej\u00f3 al Cruz Azul en la Liga MX para iniciar su primera aventura en el f\u00fatbol de Europa, luego de ser fichado por el equipo neerland\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas van unas semanas que debut\u00f3 Santiago Gim\u00e9nez con el Feyenoord en la Eredivisie. El &#8220;Bebote&#8221; incluso ya marc\u00f3 un gol y dio una asistencia, en el juego m\u00e1s reciente ante el Emmen, donde los de Rotterdam ganaron en casa 4-0. Pero hay un detalle que inquieta al entrenador Arne Slot, y es que en [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":227947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-227944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportiva"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/227944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=227944"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/227944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/227947"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=227944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=227944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=227944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}