{"id":222631,"date":"2022-07-16T08:55:27","date_gmt":"2022-07-16T13:55:27","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=222631"},"modified":"2022-07-16T08:55:33","modified_gmt":"2022-07-16T13:55:33","slug":"mayorga-y-said-se-declararon-ganadores","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/mayorga-y-said-se-declararon-ganadores\/","title":{"rendered":"Mayorga y Said se declararon ganadores"},"content":{"rendered":"\n<p>Despu\u00e9s de 15 d\u00edas de campa\u00f1a proselitista para renovar el comit\u00e9 ejecutivo de la Secci\u00f3n XV del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE), ayer se realiz\u00f3 la votaci\u00f3n en la que Julio Mayorga, candidato de la planilla naranja \u201cSomos Unidad\u201d y Said Vargas de la planilla blanca \u201cTransformaci\u00f3n sindical\u201d, se declararon ganadores.<\/p>\n\n\n\n<p>Ambos aspirantes anunciaron, a trav\u00e9s de conferencias de prensa, que los conteos de salida les daban la victoria, sin embargo ser\u00e1 hasta el domingo cuando se informen los resultados oficiales, y en consecuencia el l\u00edder que dirigir\u00e1 los trabajos del magisterio por cuatro a\u00f1os.<\/p>\n\n\n\n<p>En su mensaje, Mayorga precis\u00f3 que la votaci\u00f3n transcurri\u00f3 en normalidad y en paz, con una participaci\u00f3n entre 65 y 70 por ciento del censo magisterial, argumentando que el restante se debi\u00f3 a razones de salud por la pandemia y porque algunos trabajadores, principalmente jubilados, tuvieron complicaciones de traslado.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que de acuerdo a los datos preliminares se ubicaba nueve puntos arriba de la planilla blanca, por lo que llam\u00f3 a la unidad, respetar el derecho de las mayor\u00edas y dejar atr\u00e1s el calor de la contienda electoral.<\/p>\n\n\n\n<p>Vargas sentenci\u00f3 \u201cla mafia sindical est\u00e1 preparando sus chivas ya se fueron\u201d, asegurando tambi\u00e9n que las encuestas de salida lo colocan como el ganador de la contienda.<\/p>\n\n\n\n<p>Dijo \u201cvienen los tiempos de l\u00edder cercano, el l\u00edder que va a estar cerca de los compa\u00f1eros trabajadores de la educaci\u00f3n, un l\u00edder de tiempo completo, no les vamos a fallar, seremos los soldados de la transformaci\u00f3n sindical\u201d.<\/p>\n\n\n\n<p>Tambi\u00e9n hizo un llamado a los aspirantes a sumarse a lo que denomin\u00f3 la transformaci\u00f3n hist\u00f3rica del magisterio, \u201cla democratizaci\u00f3n de la secci\u00f3n xv lleg\u00f3, el magisterio recuper\u00f3 el sindicato para sus trabajadores\u201d.<\/p>\n\n\n\n<p>Es importante se\u00f1alar que aunque ambos candidatos declararon su victoria, ser\u00e1 hasta el pr\u00f3ximo domingo 17 de julio cuando se conozca de manera oficial al nuevo l\u00edder de la Secci\u00f3n XV del SNTE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 15 d\u00edas de campa\u00f1a proselitista para renovar el comit\u00e9 ejecutivo de la Secci\u00f3n XV del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE), ayer se realiz\u00f3 la votaci\u00f3n en la que Julio Mayorga, candidato de la planilla naranja \u201cSomos Unidad\u201d y Said Vargas de la planilla blanca \u201cTransformaci\u00f3n sindical\u201d, se declararon ganadores. Ambos [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":222632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,59,2159],"tags":[],"class_list":["post-222631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-general","category-noticias-de-hidalgo"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/222631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=222631"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/222631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/222632"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=222631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=222631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=222631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}