{"id":21919,"date":"2016-05-26T12:08:26","date_gmt":"2016-05-26T12:08:26","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2016\/05\/26\/laguna-de-voces-153\/"},"modified":"2016-05-26T12:08:26","modified_gmt":"2016-05-26T12:08:26","slug":"laguna-de-voces-153","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/laguna-de-voces-153\/","title":{"rendered":"LAGUNA DE VOCES"},"content":{"rendered":"<p style=\"text-align: justify;\">* Cuatro paredes de libertad<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Al final de cuentas, y aunque intentemos negarlo, la tierra tambi\u00e9n es un cuarto de cuatro paredes del que pocos pueden salir, y si lo hacen pesan tantas dudas que en poco son disipadas cuando observamos la luna en una noche limpia, y a la vista de un telescopio lo menos que podemos asegurar es que la fabricaron de cart\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cuando termina la vida, si antes no somos incendiados para quedar convertidos en polvo fino, igual nos encierran en una caja que es la misma habitaci\u00f3n con las posibilidades antiguas de poder escapar, es decir ninguna.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Si por esas cosas de la vida nos vemos obligados a la ausencia de una oficina que convertimos en segundo hogar, primero pensamos que extra\u00f1amos la silla de rueditas que nos permite movernos de un lado a otro, el tel\u00e9fono con altavoz que nunca funciona, los libros que se amontonan sin ning\u00fan sentido y a la espera de ser le\u00eddos, cables enredados de aparatos desaparecidos, la vieja persiana que se traba, peri\u00f3dicos viejos de lo que fuimos y ya no somos.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sin embargo nada de eso es lo que nutre el acto de extra\u00f1ar. Alguna vez pens\u00e9 que el d\u00fao de fantasmas que de vez en vez se asomaban por la puerta, y puede que as\u00ed sea.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pero hasta hace unas horas supe que era al rev\u00e9s. Resulta que es la oficina que extra\u00f1a a su ocupante, y por eso todo lo que permanec\u00eda sin vida de pronto empieza a caminar de nuevo. La extensi\u00f3n 165 suena melodiosa de pronto, y el que ya no estaba de pronto est\u00e1, lo que quiere decir que somos indispensable para que por lo menos el tel\u00e9fono cobre vida luego de meses de silencio.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No escapamos de las cuatro paredes, sean de un cuadrado, un rect\u00e1ngulo, un c\u00edrculo o la forma que sea. Son cuatro porque as\u00ed manda la costumbre y el hablar de todos los que se saben encerrados de manera moment\u00e1nea o hasta la eternidad.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Solo la ausencia nos da testimonio cierto de que hacemos falta en alguna parte. Porque el libro preferido deja de tener sentido sin el lector, y por eso pensar en el ego\u00edsmo de coleccionar vida en un librero de cad\u00e1veres. La mejor apuesta es que otros disfruten lo que nosotros, aunque se acabe por comprobar que si es tonto el que presta la novela de su preferencia, m\u00e1s lo es quien la regresa. Pero solo as\u00ed se le rinde tributo al que un d\u00eda la escribi\u00f3, que no fue para una sola persona, sino para todos los que pudiera tener a su alcance.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El hecho es que lo sin vida adquiere vida por nuestra presencia, y los pensamientos empiezan a golpear las paredes, a sonar como peque\u00f1os tamborcillos, a latir es la palabra, en un coraz\u00f3n que vuelve a emocionarse por la novedad que traer\u00e1 la edici\u00f3n del siguiente d\u00eda en el peri\u00f3dico.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Con todo y la impresionante rapidez de las redes sociales, a\u00fan buscamos rastros de nuestra existencia en los diarios, y guardamos la ocasi\u00f3n en que aparecimos en una fotograf\u00eda, la boda, el bautizo, la graduaci\u00f3n. Confeccionadores de impresos, nos emociona vernos una vez cada cuatro a\u00f1os como personajes de la noticia. Y es la \u00fanica ocasi\u00f3n que traicionamos el principio de que lo importante es la informaci\u00f3n, no quien la firme.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pero la ofician revive, y no es una simple palabra, es la certeza de que lo muerto adquiere vida. Se recupera del largo letargo, abre los ojos y nos saluda con singular belleza.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Era cierto: nos extra\u00f1aba, y por supuesto la extra\u00f1\u00e1bamos.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El principal s\u00edntoma de que la salud mejora es que a rastras o a brincos, nos posesionamos de la silla que gira, le damos una, dos, tres vueltas y sentimos el mareo absoluto de que las cuatro paredes pueden ser el encierro, o la libertad, seg\u00fan lo veamos.<\/p>\n<p style=\"text-align: justify;\">Mil gracias, hasta ma\u00f1ana.<\/p>\n<p style=\"text-align: justify;\"><a href=\"mailto:jeperalta@gmail.com\">jeperalta@gmail.com<\/a><\/p>\n<p style=\"text-align: justify;\">twitter: @JavierEPeralta<\/p>\n<p style=\"text-align: justify;\">CITA:<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El principal s\u00edntoma de que la salud mejora es que a rastras o a brincos, nos posesionamos de la silla que gira, le damos una, dos, tres vueltas y sentimos el mareo absoluto de que las cuatro paredes pueden ser el encierro, o la libertad, seg\u00fan lo veamos.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>* Cuatro paredes de libertad<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-21919","post","type-post","status-publish","format-standard","hentry","category-javier-peralta"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/21919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=21919"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/21919\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=21919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=21919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=21919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}