{"id":217508,"date":"2022-06-04T12:33:05","date_gmt":"2022-06-04T17:33:05","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=217508"},"modified":"2022-06-04T12:33:11","modified_gmt":"2022-06-04T17:33:11","slug":"bloqueo_ixmiquilpan","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/bloqueo_ixmiquilpan\/","title":{"rendered":"EL BLOQUEO REALIZADO EN PACHUCA DIO RESULTADOS"},"content":{"rendered":"\n<p>El lunes iniciar\u00e1n trabajos de reconstrucci\u00f3n en Ixmiquilpan<\/p>\n\n\n\n<p>El bloqueo realizado en diferentes arter\u00edas viales de Pachuca le dio resultados positivos a los habitantes de Ixmiquilpan, ya que finalmente se logr\u00f3 el acuerdo de que este lunes dar\u00e1n inicio los trabajos de reconstrucci\u00f3n de los da\u00f1os que dejo la inundaci\u00f3n que tuvo lugar en el mes de diciembre del a\u00f1o anterior.<\/p>\n\n\n\n<p>El grupo de manifestantes habr\u00eda llegado a Pachuca en autobuses y el contingente fue encabezado por la alcaldesa Araceli Beltr\u00e1n; quien junto con una comisi\u00f3n, lograron que se les brindar\u00e1 la atenci\u00f3n y luego de una reuni\u00f3n en el Palacio de Gobierno, lograron los acuerdos; por lo que se inform\u00f3 que este lunes se dar\u00e1 inicio a los trabajos para reparar los da\u00f1os que dej\u00f3 la inundaci\u00f3n.<\/p>\n\n\n\n<p>Como se recuerda los manifestantes implementaron bloqueos en el Viaducto R\u00edo de las Avenidas, en ambos sentidos, a la altura de colonia Palmitas, en la Glorieta Insurgentes, en ambos sentidos, sobre la Avenida Ju\u00e1rez, en la carretera M\u00e9xico-Pachuca, a la altura de la colonia de San Antonio El Desmonte y en el bulevar Colosio, en ambos sentidos, a la altura de colonia de San Cayetano.<\/p>\n\n\n\n<p>De ello la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo report\u00f3 que a las 14:30 horas se detectaron los bloqueos pero al filo de las 16:30 horas se inici\u00f3 del retiro de los bloqueos en los distintos puntos de Pachuca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes iniciar\u00e1n trabajos de reconstrucci\u00f3n en Ixmiquilpan El bloqueo realizado en diferentes arter\u00edas viales de Pachuca le dio resultados positivos a los habitantes de Ixmiquilpan, ya que finalmente se logr\u00f3 el acuerdo de que este lunes dar\u00e1n inicio los trabajos de reconstrucci\u00f3n de los da\u00f1os que dejo la inundaci\u00f3n que tuvo lugar en el [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":217510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,2159,40],"tags":[],"class_list":["post-217508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/217508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=217508"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/217508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/217510"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=217508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=217508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=217508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}