{"id":217390,"date":"2022-06-03T12:42:44","date_gmt":"2022-06-03T17:42:44","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=217390"},"modified":"2022-06-03T12:42:50","modified_gmt":"2022-06-03T17:42:50","slug":"denuncian-una-guerra-sucia-contra-petro-en-colombia","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/denuncian-una-guerra-sucia-contra-petro-en-colombia\/","title":{"rendered":"Denuncian una &#8220;guerra sucia&#8221; contra Petro en Colombia"},"content":{"rendered":"\n<p>El presidente mexicano, Andr\u00e9s Manuel L\u00f3pez Obrador, denunci\u00f3 este viernes una &#8220;guerra sucia&#8221; contra el izquierdista Gustavo Petro, candidato presidencial de la coalici\u00f3n Pacto Hist\u00f3rico en Colombia.<\/p>\n\n\n\n<p>\u201cLe mando un abrazo a Petro desde aqu\u00ed. \u00bfY saben por qu\u00e9 lo abrazo? Porque est\u00e1 enfrentando una guerra sucia de lo m\u00e1s indigna y cobarde. Todo lo que ya vimos y padecimos en M\u00e9xico&#8221;, manifest\u00f3 el mandatario en su rueda de prensa matutina.<\/p>\n\n\n\n<p>L\u00f3pez Obrador recit\u00f3 con sarcasmo los lemas que, seg\u00fan \u00e9l, utilizan contra el candidato de izquierdas, como &#8220;Petro: un peligro para Colombia, comunista, guerrillero&#8221; y &#8220;Colombia va a ser como Venezuela, etc\u00e9tera, etc\u00e9tera&#8221;.<\/p>\n\n\n\n<p>El presidente de M\u00e9xico justific\u00f3 hablar de las elecciones presidenciales en Colombia, cuya segunda vuelta ser\u00e1 el 19 de junio, con el argumento que \u00e9l tambi\u00e9n padeci\u00f3 &#8220;guerra sucia&#8221;.<\/p>\n\n\n\n<p>\u201cEl caso de Petro es porque me molesta mucho la campa\u00f1a en su contra, es de veras indigna, ruin, y es lo que ya nosotros hemos enfrentado. Yo espero que la gente en Colombia no se deje manipular y que act\u00fae con libertad y que vote por el que quiera, pero no a esa guerra sucia&#8221;, indic\u00f3.<\/p>\n\n\n\n<p>Petro, que sac\u00f3 el 40,32 % en las urnas en la primera vuelta, el 29 de mayo, se enfrentar\u00e1 por la Presidencia el 19 de junio al empresario Rodolfo Hern\u00e1ndez, que se col\u00f3 en esta segunda vuelta tras obtener el 28,15 %.<\/p>\n\n\n\n<p>Aunque se promueve como un candidato antisistema, Hern\u00e1ndez ha recibido el apoyo del oficialista Federico Guti\u00e9rrez, candidato de la derecha colombiana que qued\u00f3 en tercer lugar.<\/p>\n\n\n\n<p>\u201cCon todo, unidos todos los conservadores, y sin \u00e9tica, olvidando que la pol\u00edtica es un imperativo \u00e9tico. Y ya. Lo hago (hablar de Colombia) porque si alguien ha padecido, y me siento v\u00edctima, de esas guerras sucias, es el que les habla, desde hace a\u00f1os&#8221;, manifest\u00f3 L\u00f3pez Obrador.<\/p>\n\n\n\n<p>El mandatario mexicano compar\u00f3 la situaci\u00f3n actual en Colombia con el fraude que \u00e9l denuncia que padeci\u00f3 en 2006, cuando perdi\u00f3 la elecci\u00f3n presidencial contra el derechista Felipe Calder\u00f3n (2006-2012).<\/p>\n\n\n\n<p>Cit\u00f3 la campa\u00f1a de &#8220;L\u00f3pez Obrador: un peligro para M\u00e9xico&#8221; que crearon el consultor estadounidense Dick Morris y el publicista espa\u00f1ol Antonio Sola.<\/p>\n\n\n\n<p>\u201cEntonces por eso lo de Petro es nada m\u00e1s para decir, en cualquier lugar de la tierra, donde hay una campa\u00f1a con esas caracter\u00edsticas, (alguien) por lo general tiene el control de todos los medios. Dominan, aturden, se imponen. Est\u00e1n suplantado la voluntad libre de los ciudadanos&#8221;, insisti\u00f3.<\/p>\n\n\n\n<p>Incluso, el presidente advirti\u00f3 de un posible &#8220;fraude&#8221;.<\/p>\n\n\n\n<p>\u201cNo es solo el fraude tradicional, no. El fraude que significa que se permitan esas campa\u00f1as de desprestigio, esa guerra sucia, todo el dinero que se utiliza, los publicistas mercenarios que van de un pa\u00eds a otro prestando ese servicio\u201d, sentenci\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente mexicano, Andr\u00e9s Manuel L\u00f3pez Obrador, denunci\u00f3 este viernes una &#8220;guerra sucia&#8221; contra el izquierdista Gustavo Petro, candidato presidencial de la coalici\u00f3n Pacto Hist\u00f3rico en Colombia. \u201cLe mando un abrazo a Petro desde aqu\u00ed. \u00bfY saben por qu\u00e9 lo abrazo? Porque est\u00e1 enfrentando una guerra sucia de lo m\u00e1s indigna y cobarde. Todo lo [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":217391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36],"tags":[],"class_list":["post-217390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/217390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=217390"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/217390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/217391"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=217390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=217390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=217390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}