{"id":213763,"date":"2022-05-05T13:09:29","date_gmt":"2022-05-05T18:09:29","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=213763"},"modified":"2022-05-05T13:09:38","modified_gmt":"2022-05-05T18:09:38","slug":"estudiante-mexicana-crea-aparato-que-detecta-drogas-de-violacion-en-bebidas","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/estudiante-mexicana-crea-aparato-que-detecta-drogas-de-violacion-en-bebidas\/","title":{"rendered":"Estudiante mexicana crea aparato que detecta &#8220;drogas de violaci\u00f3n&#8221; en bebidas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Detectar sedantes en las bebidas alcoh\u00f3licas es lo que consigue el dispositivo que invent\u00f3 la estudiante mexicana Arely Salcedo, a quien se le ocurri\u00f3 esta idea despu\u00e9s de que una amiga suya fuera v\u00edctima en una fiesta de una &#8220;droga de violaci\u00f3n&#8221; que le pusieron en el trago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el hecho \u2014en donde a su amiga le salvaron la vida en una ambulancia\u2014 la alumna de noveno semestre de ingenier\u00eda biom\u00e9dica en la Universidad Aut\u00f3noma de Quer\u00e9taro (UAQ), en el centro del pa\u00eds, busc\u00f3 una soluci\u00f3n, seg\u00fan cuenta este jueves en entrevista con Efe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, dise\u00f1\u00f3 un aparato para detectar en las bebidas alcoh\u00f3licas la xilacina, una de las drogas m\u00e1s usadas por los agresores sexuales para sedar a sus v\u00edctimas antes de violarlas y que, en muchos casos, puede terminar en muerte por sobredosis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa xilacina es un sedante veterinario muy potente, es analg\u00e9sico y somn\u00edfero, casi siempre lo utilizan en animales muy grandes como caballos y vacas. Lo malo es que los agresores no saben esto, lo peligroso es que se les pase la mano, que es lo que generalmente pasa&#8221;, comenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La futura ingeniera afirma que por ahora no existe una herramienta funcional que permita identificar la xilacina u otras sustancias en la bebida para prevenir los ataques, de ah\u00ed la necesidad de una barrera primaria ante esta problem\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HERRAMIENTA CONTRA LA VIOLENCIA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El invento es una herramienta m\u00e1s para frenar la ola de violencia contra las mujeres en M\u00e9xico, pa\u00eds donde asesinan a m\u00e1s de 10 mujeres al d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y se da en medio de recientes casos que han sacudido al pa\u00eds, como el de la joven Debanhi Escobar, de 18 a\u00f1os, que apareci\u00f3 muerta en un motel del norte\u00f1o estado de Nuevo Le\u00f3n tras precisamente ir a una fiesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salcedo relata que intentaron drogar a su amiga en una discoteca, donde es muy dif\u00edcil identificar si la persona est\u00e1 drogada por el amontonamiento de personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Afortunadamente, con ella pudimos hacer que viniera la ambulancia y la atendiera, pero es algo muy, muy feo. Te das cuenta de lo vulnerable que eres y que puede pasarle a cualquier persona realmente\u201d, manifiesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante el clima de violencia, en Quer\u00e9taro ya hay personas interesadas en el dispositivo. Como Mar\u00eda Fernanda Trejo, quien ha afrontado y conoce a v\u00edctimas de situaciones de riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA la hermana de mi cu\u00f1ado se la intentaron llevar, con lo mismo, la intentaron drogar, entonces es realmente importante para nosotras como mujeres y tambi\u00e9n para los chicos, porque no dudo que tambi\u00e9n les pudiera pasar\u201d, opin\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00d3MO FUNCIONA?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salcedo detalla que el dispositivo cuenta con un sensor que tiene como base una celda electroqu\u00edmica, que permite oxido-reducir la mol\u00e9cula de xilacina en la bebida preparada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mol\u00e9cula de xilacina queda intacta y es muy f\u00e1cil detectarla porque el l\u00edmite de detecci\u00f3n es muy peque\u00f1o, por lo que algo menor a una gota puede ser detectada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque a\u00fan no tiene nombre, el proyecto acaba de concluir la etapa de ensayo, luego de probarse en distintas bebidas, con diferentes tipos de alcohol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al considerar que esta fase fue exitosa, la inventora inici\u00f3 con el prototipado del producto, que prev\u00e9 se convierta en un instrumento peque\u00f1o y de f\u00e1cil acceso econ\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYa lo hemos probado en muchas bebidas preparadas como whisky, ron, tequila, vodka. Tambi\u00e9n con refrescos, y es muy exitosa&#8221;, menciona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El producto final esperamos que sea algo accesible y muy portable, lo imaginamos como una vara agitadora de bebidas en donde el usuario pueda menear su bebida y, si est\u00e1 la presencia de la mol\u00e9cula, pueda prender un (foco) led y entonces t\u00fa ya sabes si es seguro o no beber\u201d, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan as\u00ed, reconoce que para que el dispositivo se vuelva una realidad podr\u00eda tardar un a\u00f1o m\u00e1s, pues se buscan socios que quieran invertir en el proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se ha establecido como meta crear un multisensor que pueda detectar otras drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara m\u00ed es muy gratificante porque decid\u00ed estudiar esta carrera, porque te dan las herramientas para poder resolver cosas y necesidades sociales. Muchas veces estamos buscando el hilo negro dentro de la investigaci\u00f3n, pero es muy importante el atender estos temas de seguridad humana&#8221;, manifiesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan de Dios Galindo, profesor investigador de la UAQ y asesor del proyecto, ahonda en que esta herramienta reportar\u00eda en tiempo real la presencia de esta droga, una tecnolog\u00eda que generalmente se utiliza en el an\u00e1lisis de cad\u00e1veres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa idea de ella surgi\u00f3 debido a que actualmente hay muchos problemas de seguridad humana y la universidad est\u00e1 comprometida en hacer ciencia no nada m\u00e1s por hacerla, sino para que tenga un compromiso social&#8221;, subraya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detectar sedantes en las bebidas alcoh\u00f3licas es lo que consigue el dispositivo que invent\u00f3 la estudiante mexicana Arely Salcedo, a quien se le ocurri\u00f3 esta idea despu\u00e9s de que una amiga suya fuera v\u00edctima en una fiesta de una &#8220;droga de violaci\u00f3n&#8221; que le pusieron en el trago. Tras el hecho \u2014en donde a su [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":213764,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36,2162],"tags":[],"class_list":["post-213763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacion","category-noticias-diario-ultimas-de-queretaro"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/213763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=213763"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/213763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/213764"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=213763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=213763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=213763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}