{"id":212352,"date":"2022-04-23T10:34:21","date_gmt":"2022-04-23T15:34:21","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=212352"},"modified":"2022-04-23T10:41:43","modified_gmt":"2022-04-23T15:41:43","slug":"aseguran-dos-camionetas-cargadas-con-huachicol","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/aseguran-dos-camionetas-cargadas-con-huachicol\/","title":{"rendered":"Aseguran dos camionetas cargadas con huachicol"},"content":{"rendered":"\n<p>Tepeapulco.- Elementos de la Polic\u00eda Estatal, destacamentados en Ciudad Sahag\u00fan, aseguraron dos camionetas abandonadas por presuntos huachicoleros, con m\u00e1s de dos mil litros de hidrocarburo de procedencia il\u00edcita.<\/p>\n\n\n\n<p>Los hechos se suscitaron al filo de las 05:00 horas de ayer viernes, cuando en su rutina de vigilancia, sobre la carretera interestatal Tepeapulco-Cuautepec, los elementos estatales se percataron que sobre un camino de terracer\u00eda, estaban varadas dos camionetas de carga.<\/p>\n\n\n\n<p>Durante la inspecci\u00f3n ocular, al interior de las dos unidades solo encontraron las llaves de encendido puestas, sin ser posible dar con los presuntos huachicoleros.<\/p>\n\n\n\n<p>En el aseguramiento de las unidades, concluyeron que ambas cuentan con reporte de robo vigente.<\/p>\n\n\n\n<p>En el parte informativo, indicaron que las unidades son: una camioneta marca Nissan, tipo NP300 Frontier, color cabina gris con caja seca&nbsp; color blanca, con solo la placa trasera&nbsp; de circulaci\u00f3n SN-14-442, la cual cuenta con reporte&nbsp; de robo vigente en Repuve, y estaba&nbsp; cargada con 2 contenedores de pl\u00e1stico: uno con capacidad de mil litros completamente vac\u00edo, el otro contenedor&nbsp; con&nbsp; capacidad de 1,200 litros abastecido con l\u00edquido al parecer hidrocarburo, as\u00ed como un tambo con capacidad de 200 litros abastecido al 85 por ciento.<\/p>\n\n\n\n<p>La segunda unidad, es una camioneta Nissan, tipo NP300 Frontier, de color Rojo, modelo 2021 con placas de circulaci\u00f3n Y08-XXW, la cual estaba cargada con dos contenedores de pl\u00e1stico&nbsp; con capacidad de mil litros, cada uno abastecidos al 90 por ciento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tepeapulco.- Elementos de la Polic\u00eda Estatal, destacamentados en Ciudad Sahag\u00fan, aseguraron dos camionetas abandonadas por presuntos huachicoleros, con m\u00e1s de dos mil litros de hidrocarburo de procedencia il\u00edcita. Los hechos se suscitaron al filo de las 05:00 horas de ayer viernes, cuando en su rutina de vigilancia, sobre la carretera interestatal Tepeapulco-Cuautepec, los elementos estatales [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":212353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,2159,40],"tags":[],"class_list":["post-212352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/212352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=212352"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/212352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/212353"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=212352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=212352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=212352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}