{"id":209661,"date":"2022-04-01T07:58:58","date_gmt":"2022-04-01T13:58:58","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=209661"},"modified":"2022-04-01T07:59:08","modified_gmt":"2022-04-01T13:59:08","slug":"vinculan-a-proceso-al-ex-presidente-de-apan-jose-lopez-calderon","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/vinculan-a-proceso-al-ex-presidente-de-apan-jose-lopez-calderon\/","title":{"rendered":"Vinculan a proceso al ex presidente de Apan, Jos\u00e9 L\u00f3pez Calder\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apan.- Por \u201cfalsedad de declaraciones\u201d, un Juez Federal imput\u00f3 penalmente al expresidente municipal de Apan, Jos\u00e9 Guadalupe L\u00f3pez Calder\u00f3n, y a siete integrantes de su familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La audiencia inicial se llev\u00f3 a cabo el pasado 28 de marzo en un juzgado federal, y bajo la Causa Penal 22\/2022, derivada de la carpeta de investigaci\u00f3n FED\/HGO\/PACH\/0003678\/2018, y en esta fueron vinculados a proceso Jos\u00e9 Guadalupe L\u00f3pez Calder\u00f3n, expresidente municipal, y sus familiares: Delia Lozada Romero, Marcos L\u00f3pez Calder\u00f3n, as\u00ed como a Jos\u00e9 Remigio, Jos\u00e9 Guadalupe, Armando, Delia, Laura Georgina y Mar\u00eda del Carmen, todos de apellidos L\u00f3pez Lazada, quienes podr\u00e1n enfrentar hasta 6 a\u00f1os de prisi\u00f3n por el delito de \u201cfalsedad de declaraciones ante la autoridad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a la sentencia dictada por el Juez Federal, en los 11 amparos que fueron promovidos ante una autoridad federal, se incurri\u00f3 en falsedad de declaraciones para obtener los beneficios y seguir gozando de un bien inmueble, el cual ocupan ilegalmente; este se encuentra ubicado en la comunidad de Santiago Tetlapayac, municipio de Almoloya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HABLA EL ACTUAL DUE\u00d1O DE LA EX HACIENDA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista con <em>Diario Plaza Ju\u00e1rez<\/em>, Jos\u00e9 Antonio Pascal Calvillo, actual due\u00f1o de la ex hacienda de Tetlapayac, relat\u00f3 que los ahora vinculados a proceso, han violado flagrantemente la ley durante a\u00f1os, ya que han presentado 11 amparos en donde declaran \u201cbajo protesta de decir la verdad\u201d, y dan hechos falsos, argumentando que son los leg\u00edtimos propietarios de la Hacienda en menci\u00f3n,&nbsp;omitiendo los hechos reales, como lo es que han sido o\u00eddos y vencidos en un Juicio Hipotecario por no pagar las deudas contra\u00eddas y que suman millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Antonio Pascal Calvillo, en la entrevista dijo que desde el a\u00f1o 2015, se present\u00f3 en el juzgado 14 de la Ciudad de M\u00e9xico, donde obtuvo la propiedad de la ex Hacienda Tetlapayac, tras ser el mejor postor, siendo la mejor propuesta en el remate judicial en segunda almoneda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, indic\u00f3 que la sentencia dictada en esa fecha y la cual fue dada por el juez del Juzgado 14, le otorg\u00f3 la leg\u00edtima posesi\u00f3n de la propiedad en litigio, la cual fue impugnada mediante amparo, en su momento oportuno, por los ahora imputados, y mismo que les fue rechazado por el mismo juzgador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se\u00f1al\u00f3 que, dentro de los plazos marcados por la ley, presentaron una revisi\u00f3n de la sentencia de la que tambi\u00e9n obtuvieron una resoluci\u00f3n negativa, pero con este dictamen en contra, tanto del juicio de remate como la sentencia dictada por el Juez, se le otorg\u00f3 la raz\u00f3n y la propiedad del inmueble en disputa a Pascal Calvillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su relator\u00eda, declar\u00f3 que el inmueble de la ex hacienda de Tetlapayac, ya sali\u00f3 de la esfera del patrimonio de Jos\u00e9 Guadalupe L\u00f3pez Calder\u00f3n y no le pertenece m\u00e1s, ello por haber llevado a la Hacienda a ser objeto de un \u201cRemate Judicial\u201d por las deudas contra\u00eddas hace m\u00e1s de 20 a\u00f1os, en donde los mismos acreedores iniciaron diversos juicios por fraude y de los cuales no hizo el pago en su oportuno momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pascal Calvillo, hizo menci\u00f3n que el mes de noviembre del a\u00f1o 2021, empez\u00f3 una demanda de car\u00e1cter penal ante la Fiscal\u00eda General del Rep\u00fablica, la cual se inici\u00f3 bajo la carpeta de investigaci\u00f3n FED\/HGO\/PACH\/0003678\/2018, asentada ante la Fiscal\u00eda, misma que deriv\u00f3 en esta causa penal, adem\u00e1s dijo que en su momento esta fue suspendida por injerencias externas a este conflicto, por lo que hubo necesidad de alargar este proceso legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apan.- Por \u201cfalsedad de declaraciones\u201d, un Juez Federal imput\u00f3 penalmente al expresidente municipal de Apan, Jos\u00e9 Guadalupe L\u00f3pez Calder\u00f3n, y a siete integrantes de su familia. La audiencia inicial se llev\u00f3 a cabo el pasado 28 de marzo en un juzgado federal, y bajo la Causa Penal 22\/2022, derivada de la carpeta de investigaci\u00f3n FED\/HGO\/PACH\/0003678\/2018, [&hellip;]<\/p>\n","protected":false},"author":69,"featured_media":209662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2159,40],"tags":[],"class_list":["post-209661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/209661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=209661"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/209661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/209662"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=209661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=209661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=209661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}