{"id":208464,"date":"2022-03-21T12:32:47","date_gmt":"2022-03-21T18:32:47","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=208464"},"modified":"2022-03-21T12:32:56","modified_gmt":"2022-03-21T18:32:56","slug":"aguilas_diablos","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/aguilas_diablos\/","title":{"rendered":"Las \u00c1guilas golean con pol\u00e9mica arbitral a los Diablos\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>MARCADOR FINAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AM\u00c9RICA 3-0 TOLUCA&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al Am\u00e9rica le bastaron cerca de 20 minutos, primero para liquidar al Toluca y despu\u00e9s para volver a tener un triunfo en el Estadio Azteca, que no lograban desde octubre del 2021. Con Fernando Ortiz como interino, sin claridad sobre qui\u00e9n llegar\u00e1 al banquillo que dej\u00f3 Santiago Solari, las \u00c1guilas aprovecharon la crisis de los Diablos Rojos de Nacho Ambriz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras Am\u00e9rica llegaba, concretaba e intentaba, el Toluca evidenciaba su falta de ideas, de futbol. Roger Mart\u00ednez al 6&#8242; abri\u00f3 el marcador con un pol\u00e9mico gol en posici\u00f3n adelantada, pero que desde el VAR dieron por bueno. Los de Coapa siguieron y encontraron una falta al borde del \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta fue aprovechada por Diego Vald\u00e9s, que de larga distancia acomod\u00f3 el bal\u00f3n en la porter\u00eda, posteriormente, llegaron dos goles m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARCADOR FINAL AM\u00c9RICA 3-0 TOLUCA&nbsp; Al Am\u00e9rica le bastaron cerca de 20 minutos, primero para liquidar al Toluca y despu\u00e9s para volver a tener un triunfo en el Estadio Azteca, que no lograban desde octubre del 2021. Con Fernando Ortiz como interino, sin claridad sobre qui\u00e9n llegar\u00e1 al banquillo que dej\u00f3 Santiago Solari, las \u00c1guilas [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":208470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-208464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportiva"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/208464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=208464"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/208464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/208470"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=208464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=208464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=208464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}