{"id":208222,"date":"2022-03-19T09:20:57","date_gmt":"2022-03-19T15:20:57","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=208222"},"modified":"2022-03-19T09:21:09","modified_gmt":"2022-03-19T15:21:09","slug":"como-corregir-datos-en-certificado-de-vacunacion","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/como-corregir-datos-en-certificado-de-vacunacion\/","title":{"rendered":"C\u00f3mo corregir datos en Certificado de Vacunaci\u00f3n"},"content":{"rendered":"\n<p>El Instituto de Transparencia, Acceso a la Informaci\u00f3n P\u00fablica Gubernamental y Protecci\u00f3n de Datos Personales del Estado de Hidalgo (ITAIH) comparte el procedimiento para solicitar la rectificaci\u00f3n de Datos Personales en el Certificado de Vacunaci\u00f3n a la Secretar\u00eda de Salud Federal.<\/p>\n\n\n\n<p>El Certificado debe contener nombre completo, CURP, la o las dosis que se recibieron, la marca y el lote del biol\u00f3gico; si alguno de los datos es err\u00f3neo se debe acudir al Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI).<\/p>\n\n\n\n<p>Hay que ingresar a la Plataforma Nacional de Transparencia (PNT) <a href=\"http:\/\/www.plataformadetransparencia.org.mx\">www.plataformadetransparencia.org.mx<\/a> y seguir el procedimiento:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ingresar o registrarse, la cuenta se puede crear mediante redes sociales,<\/li><li>Una vez dentro dar clic en solicitudes y en datos personales,<\/li><li>Seleccionar el derecho ARCOP de rectificaci\u00f3n,&nbsp;<\/li><li>Especificar los datos incorrectos y agregar la evidencia.<\/li><li>Llenar el formulario y elegir Federaci\u00f3n-Secretar\u00eda de Salud,<\/li><li>Terminar de capturar la solicitud y enviar.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Transparencia, Acceso a la Informaci\u00f3n P\u00fablica Gubernamental y Protecci\u00f3n de Datos Personales del Estado de Hidalgo (ITAIH) comparte el procedimiento para solicitar la rectificaci\u00f3n de Datos Personales en el Certificado de Vacunaci\u00f3n a la Secretar\u00eda de Salud Federal. El Certificado debe contener nombre completo, CURP, la o las dosis que se recibieron, [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":208223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-208222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/208222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=208222"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/208222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/208223"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=208222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=208222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=208222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}