{"id":20793,"date":"2016-05-08T16:08:27","date_gmt":"2016-05-08T16:08:27","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2016\/05\/08\/no-pondremos-todos-los-huevos-en-una-sola-canasta-omar-fayad\/"},"modified":"2016-05-08T16:08:27","modified_gmt":"2016-05-08T16:08:27","slug":"no-pondremos-todos-los-huevos-en-una-sola-canasta-omar-fayad","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/no-pondremos-todos-los-huevos-en-una-sola-canasta-omar-fayad\/","title":{"rendered":"No pondremos todos los huevos en una sola canasta: Omar Fayad"},"content":{"rendered":"<p>EN PACHUCA<\/p>\n<p>El candidato a la gubernatura se dijo listo para el debate<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00a0<\/p>\n<p>El candidato a la gubernatura del estado de Hidalgo por la coalici\u00f3n \u201cUn Hidalgo con Rumbo\u201d, Omar Fayad Meneses, asever\u00f3 que en su proyecto de trabajo no est\u00e1n esperanzados a grandes proyectos sino a dar continuidad a los que se quedan pendientes y a crear otros que generen bienestar para la poblaci\u00f3n, para que no vuelva a suceder lo que con el proyecto del aeropuerto y la refiner\u00eda que no se concretaron en la entidad.<\/p>\n<p>\u00a0<\/p>\n<p>Ante esta situaci\u00f3n, Fayad Meneses argument\u00f3, \u201cno pondremos todos los huevos en una sola canasta\u201d y agreg\u00f3 \u201cdebemos apostar por varios proyectos y no estar esperanzados como lo estuvimos con el aeropuerto, o cuando cre\u00edmos que tendr\u00edamos la refiner\u00eda m\u00e1s grande del pa\u00eds, hoy es tiempo de apostar por m\u00e1s proyectos que podamos concretar\u201d.<\/p>\n<p>\u00a0<\/p>\n<p>Lo anterior en un acto proselitista realizado con vecinos y locatarios de la colonia Valle de San Javier en la capital hidalguense, donde Fayad Meneses se hizo acompa\u00f1ar del candidato a\u00a0 diputado local y las candidatas a diputada local y a presidenta municipal.<\/p>\n<p>\u00a0<\/p>\n<p>El candidato del tricolor se\u00f1al\u00f3 que una de las principales demandas de la gente en dicha zona versa sobre el tema de seguridad, por lo que se comprometi\u00f3 a trabajar en este sentido de la mano con la que dijo \u201cser\u00e1 la presidenta municipal de Pachuca\u201d, Mirna Hern\u00e1ndez Morales, por lo anterior destac\u00f3 el punto seis de su plataforma, en el que propone un sistema integral de videovigilancia, as\u00ed como algunos convenios con el sector comercial a fin de que se pueda coadyuvar en la detenci\u00f3n de los delincuentes y amantes de lo ajeno.<\/p>\n<p>\u00a0<\/p>\n<p>En otro tema, el candidato dijo estar listo para el debate que realizar\u00e1 el Instituto Estatal Electoral de Hidalgo (IEEH), y se\u00f1al\u00f3 que s\u00f3lo espera que le alcance el tiempo para dar a conocer todas su propuestas, ya que ir\u00e1 a presentar sus propuestas no a denostar ni a tener enfrentamientos como los que parece buscar la oposici\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>Por lo anterior y tras el cuestionamiento sobre su actuar en dicho encuentro, el candidato del tricolor destac\u00f3 que est\u00e1 listo para presentar propuestas y asever\u00f3 que en caso de que tenga que contestar alg\u00fan se\u00f1alamiento lo har\u00e1 con la propiedad y madurez pol\u00edtica que le ha caracterizado, tal y como sucedi\u00f3 en el encuentro que sostuvieron en el Tec de Monterrey hace algunos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EN PACHUCA El candidato a la gubernatura se dijo listo para el debate<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-20793","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/20793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=20793"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/20793\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=20793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=20793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=20793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}