{"id":203416,"date":"2022-02-14T12:35:33","date_gmt":"2022-02-14T18:35:33","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=203416"},"modified":"2022-02-14T12:35:45","modified_gmt":"2022-02-14T18:35:45","slug":"pintan-mural-en-mexico-pidiendo-justicia-por-los-seis-periodistas-asesinados","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/pintan-mural-en-mexico-pidiendo-justicia-por-los-seis-periodistas-asesinados\/","title":{"rendered":"Pintan mural en M\u00e9xico pidiendo justicia por los seis periodistas asesinados"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Varios artistas pintaron un mural en el c\u00e9ntrico barrio de la Roma de Ciudad de M\u00e9xico para pedir justicia por los seis periodistas asesinados en lo que va de a\u00f1o en el pa\u00eds y reclamar la libertad para informar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El artista Gabriel Macotela fue el que convoc\u00f3 a sus compa\u00f1eros a pintar las vallas de este lugar en el que anteriormente hab\u00edan reclamado, a trav\u00e9s de su arte, justicia para las v\u00edctimas de feminicidio o para las personas desaparecidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Los artistas, los intelectuales, estamos apoyando a esta gente maravillosa que son los periodistas, que sin ellos no sabr\u00edamos la realidad, por ellos conocemos la realidad de lo que pasa&#8221;, dijo a Efe Macotela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de las vallas pintaron diferentes motivos, escribieron los nombres de los seis periodistas asesinados en 2022 y dieron un especial protagonismo al concepto de libertad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Estoy pintando la estatua de la libertad que ha sido icono fundamental de la libertad, de los principios fundamentales de lo que es la democracia y creo que es lo que estamos perdiendo, un pa\u00eds democr\u00e1tico&#8221;, comparti\u00f3 Javier C\u00f3rdoba, otro de los artistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magali \u00c1vila, artista visual, relat\u00f3 que la intervenci\u00f3n de las vallas habla del miedo y de los medios de comunicaci\u00f3n. &#8220;Creo que hay demasiado miedo a expresar lo que realmente sucede y por eso tambi\u00e9n estamos muy desinformados&#8221;, consider\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Macotela consider\u00f3, adem\u00e1s, que el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, est\u00e1 siendo &#8220;muy intolerante&#8221; con los periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No est\u00e1n siendo respetados, se me hace incre\u00edble, yo no esperaba una respuesta as\u00ed del presidente, y por eso estamos aqu\u00ed&#8221;, sentenci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto, en referencia a las cr\u00edticas que el presidente hace recurrentemente a ciertos medios y comunicadores durante su habitual conferencia de prensa matutina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viernes, L\u00f3pez Obrador exhibi\u00f3 en su conferencia diaria el supuesto sueldo del periodista Carlos Loret de Mola, ante lo que el comunicador public\u00f3 en Twitter \u201cEl presidente est\u00e1 enfurecido, est\u00e1 fuera de s\u00ed\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De este enfrentamiento surgi\u00f3 en Twitter Space el Hastag #TodossomosLoret, que tuvo m\u00e1s de 60.000 apoyos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y la batalla no termina, ni contra Loret de Mola ni contra otros periodistas y medios a los que el presidente critica y exhibe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPese a la violencia contra la prensa en el pa\u00eds, que suma seis periodistas asesinados en lo que va de a\u00f1o, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador calific\u00f3 este viernes a varios comunicadores de &#8216;mercenarios&#8217; y exhibi\u00f3 el salario del conductor Carlos Loret de Mola&#8221;, denunci\u00f3 la organizaci\u00f3n Art\u00edculo 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De 2000 a la fecha, Art\u00edculo 19 ha documentado 149 asesinatos de periodistas en M\u00e9xico, en posible relaci\u00f3n con su labor. Del total, 137 son hombres y 12 son mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De estos, 47 se registraron durante el mandato anterior del presidente Enrique Pe\u00f1a Nieto (2012-2018) y 29 en el actual de Andr\u00e9s Manuel L\u00f3pez Obrador (2018-2024).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Varios artistas pintaron un mural en el c\u00e9ntrico barrio de la Roma de Ciudad de M\u00e9xico para pedir justicia por los seis periodistas asesinados en lo que va de a\u00f1o en el pa\u00eds y reclamar la libertad para informar. El artista Gabriel Macotela fue el que convoc\u00f3 a sus compa\u00f1eros a pintar las vallas de [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":203417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-203416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/203416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=203416"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/203416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/203417"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=203416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=203416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=203416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}