{"id":199347,"date":"2022-01-15T13:33:28","date_gmt":"2022-01-15T19:33:28","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=199347"},"modified":"2022-01-15T13:33:38","modified_gmt":"2022-01-15T19:33:38","slug":"imss-ofrece-cursos-en-linea-para-cuidado-de-pacientes-covid","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/imss-ofrece-cursos-en-linea-para-cuidado-de-pacientes-covid\/","title":{"rendered":"IMSS ofrece cursos en l\u00ednea para cuidado de pacientes Covid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">(EL UNIVERSAL) Para reforzar el autocuidado y el de pacientes con Covid-19 que cursan la enfermedad en casa, el Instituto Mexicano del Seguro Social (IMSS) puso a disposici\u00f3n de la poblaci\u00f3n cursos en l\u00ednea, lo que permitir\u00e1 cortar cadenas de contagio entre los integrantes de una familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Seguro Social lanz\u00f3 la plataforma educativa Cursos en L\u00ednea CLIMSS https:\/\/climss.imss.gob.mx\/ en marzo de 2020, con el curso &#8220;Todos contra la epidemia Covid-19&#8221; de acceso gratuito para la poblaci\u00f3n, empleadores de instituciones, empresas e industrias, con el objetivo de brindar elementos te\u00f3ricos y pr\u00e1cticos para comprender qu\u00e9 es el Coronavirus y c\u00f3mo limitar su propagaci\u00f3n y contagio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la fecha, se han registrado 18.3 millones de inscripciones en CLIMSS, de los cu\u00e1les m\u00e1s de 16 millones han sido para cursos sobre Covid-19, lo que representa el 88 por ciento. De este universo, el 50 por ciento fueron mujeres y la otra mitad hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el Instituto es importante identificar la sintomatolog\u00eda relacionada a la variante \u00f3micron, que es m\u00e1s leve respecto a la delta; una vez que se tiene alg\u00fan s\u00edntoma es importante el confinamiento en casa para acelerar el proceso de recuperaci\u00f3n y evitar contagiar a m\u00e1s personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ala que para tener un mejor manejo de pacientes con Covid-19 en casa el IMSS tiene cursos en l\u00ednea con duraci\u00f3n de dos a tres horas y est\u00e1n disponibles para la poblaci\u00f3n abierta, adem\u00e1s generan una validaci\u00f3n al concluirlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Lo m\u00e1s importante de estos cursos en l\u00ednea es que se orienta a la poblaci\u00f3n sobre los cuidados que se deben de tener en la higiene en casa y en los espacios donde se recupera el paciente, el autocuidado de los cuidadores&#8221;, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, c\u00f3mo atender a un enfermo que adem\u00e1s padece comorbilidades, as\u00ed como el tipo de alimentos que se deben preparar, entre otras instrucciones que contribuyen a un manejo seguro de una persona enferma, as\u00ed como cortar las cadenas de contagio dentro del seno familiar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la pandemia se ha detectado que cuando una persona enferma de Covid-19 y no se tienen los cuidados correspondientes cuando se cursa la recuperaci\u00f3n en casa, el resto de la familia queda expuesta al contagio, por ello es importante la autocapacitaci\u00f3n mediante los cursos que ofrece el IMSS en l\u00ednea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EL UNIVERSAL) Para reforzar el autocuidado y el de pacientes con Covid-19 que cursan la enfermedad en casa, el Instituto Mexicano del Seguro Social (IMSS) puso a disposici\u00f3n de la poblaci\u00f3n cursos en l\u00ednea, lo que permitir\u00e1 cortar cadenas de contagio entre los integrantes de una familia. El Seguro Social lanz\u00f3 la plataforma educativa Cursos [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":193892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36],"tags":[],"class_list":["post-199347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/199347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=199347"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/199347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/193892"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=199347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=199347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=199347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}