{"id":196716,"date":"2021-12-25T02:57:29","date_gmt":"2021-12-25T08:57:29","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=196716"},"modified":"2021-12-25T02:57:39","modified_gmt":"2021-12-25T08:57:39","slug":"semaforo-covid-en-mexico-cierra-el-2021-con-28-estados-en-verde","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/semaforo-covid-en-mexico-cierra-el-2021-con-28-estados-en-verde\/","title":{"rendered":"Sem\u00e1foro Covid en M\u00e9xico cierra el 2021 con 28 estados en verde"},"content":{"rendered":"\n<p>(EL UNIVERSAL) La Secretar\u00eda de Salud inform\u00f3 que para las pr\u00f3ximas dos semanas 28 estados de la Rep\u00fablica cerrar\u00e1n el a\u00f1o en sem\u00e1foro epidemiol\u00f3gico en verde, mientras que cuatro estados estar\u00e1n en riesgo medio.<\/p>\n\n\n\n<p>De acuerdo al reporte de la dependencia los estados que pasar\u00e1n fin de a\u00f1o en color amarillo son Aguascalientes, Baja California, Sonora y Chihuahua.<\/p>\n\n\n\n<p>Mientras que los estados en color verde en el per\u00edodo vigente del 27 de diciembre al 9 de enero son:<\/p>\n\n\n\n<p>-Baja California Sur<\/p>\n\n\n\n<p>-Sinaloa<\/p>\n\n\n\n<p>-Durango<\/p>\n\n\n\n<p>-Coahuila<\/p>\n\n\n\n<p>-Nuevo Le\u00f3n<\/p>\n\n\n\n<p>-Zacatecas<\/p>\n\n\n\n<p>-Tamaulipas<\/p>\n\n\n\n<p>-San Luis Potos\u00ed<\/p>\n\n\n\n<p>-Nayarit<\/p>\n\n\n\n<p>-Jalisco<\/p>\n\n\n\n<p>-Guanajuato<\/p>\n\n\n\n<p>-Colima<\/p>\n\n\n\n<p>-Quer\u00e9taro<\/p>\n\n\n\n<p>-Hidalgo<\/p>\n\n\n\n<p>-Veracruz<\/p>\n\n\n\n<p>-Michoac\u00e1n<\/p>\n\n\n\n<p>-Estado de M\u00e9xico<\/p>\n\n\n\n<p>-Guerrero<\/p>\n\n\n\n<p>-Tlaxcala<\/p>\n\n\n\n<p>-Ciudad de M\u00e9xico<\/p>\n\n\n\n<p>-Puebla<\/p>\n\n\n\n<p>-Morelos<\/p>\n\n\n\n<p>-Oaxaca<\/p>\n\n\n\n<p>-Tabasco<\/p>\n\n\n\n<p>-Campeche<\/p>\n\n\n\n<p>-Chiapas<\/p>\n\n\n\n<p>-Yucat\u00e1n<\/p>\n\n\n\n<p>-Quintana Roo<\/p>\n\n\n\n<p>Vacunaci\u00f3n contra Covid en M\u00e9xico<\/p>\n\n\n\n<p>Este viernes se cumple un a\u00f1o del inicio de la Estrategia Nacional de Vacunaci\u00f3n, que se ha llevado a cabo en diferentes fases: primero, personal de salud que atiende pacientes Covid-19; despu\u00e9s, personas mayores de 60 a\u00f1os, del sector educativo, de 50 a 59, de 40 a 49, de 30 a 39 y de 18 a 29.<\/p>\n\n\n\n<p>Actualmente, contin\u00faa la vacunaci\u00f3n para quienes por alguna raz\u00f3n no pudieron hacerlo en su momento, se inmuniza a j\u00f3venes de 15 a 17 y se aplica el refuerzo a personas mayores de 60 a\u00f1os.<\/p>\n\n\n\n<p>El subsecretario de Prevenci\u00f3n y Promoci\u00f3n de la Salud, Hugo L\u00f3pez-Gatell inform\u00f3 que el 21 de diciembre se aplicaron 392 mil 345 dosis de vacunas contra Covid-19. Lo que en su totalidad suman en M\u00e9xico 147 millones 489 mil 369 dosis suministradas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EL UNIVERSAL) La Secretar\u00eda de Salud inform\u00f3 que para las pr\u00f3ximas dos semanas 28 estados de la Rep\u00fablica cerrar\u00e1n el a\u00f1o en sem\u00e1foro epidemiol\u00f3gico en verde, mientras que cuatro estados estar\u00e1n en riesgo medio. De acuerdo al reporte de la dependencia los estados que pasar\u00e1n fin de a\u00f1o en color amarillo son Aguascalientes, Baja California, [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":191025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36],"tags":[],"class_list":["post-196716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/196716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=196716"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/196716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/191025"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=196716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=196716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=196716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}