{"id":192947,"date":"2021-11-28T07:45:25","date_gmt":"2021-11-28T13:45:25","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=192947"},"modified":"2021-11-28T07:45:35","modified_gmt":"2021-11-28T13:45:35","slug":"ceremonia-de-titulacion-en-la-escuela-de-musica-de-hidalgo","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/ceremonia-de-titulacion-en-la-escuela-de-musica-de-hidalgo\/","title":{"rendered":"Ceremonia de Titulaci\u00f3n en la Escuela de M\u00fasica de Hidalgo"},"content":{"rendered":"\n<p>En ceremonia c\u00edvica encabezada por Ver\u00f3nica Kugel, subsecretaria de Patrimonio y Fomento Cultural, y Aar\u00f3n David Tr\u00e1pala Mart\u00ednez, subdirector acad\u00e9mico de la Escuela de M\u00fasica del Estado de Hidalgo (EMEH) se hizo la entrega de&nbsp; t\u00edtulos profesionales a siete estudiantes de Licenciatura en M\u00fasica e Ingenier\u00eda en Audio.<\/p>\n\n\n\n<p>Se inform\u00f3 que en lo que va del a\u00f1o, la EMEH ha entregado 24 diplomas, que se suman a los 21 otorgados durante la pandemia.&nbsp;<\/p>\n\n\n\n<p>Tr\u00e1pala Mart\u00ednez, se\u00f1al\u00f3 que con el apoyo que brinda la Secretar\u00eda de Cultura de Hidalgo, la eficiencia terminal se ha fortalecido, a pesar de la situaci\u00f3n actual derivada de la pandemia por Covid-19. Y aprovech\u00f3 para felicitar a los egresados por obtener el t\u00edtulo que les permite respaldar la formaci\u00f3n profesional.<\/p>\n\n\n\n<p>Por su parte, Ver\u00f3nica Kugel reconoci\u00f3 la labor que se hace en materia art\u00edstica y cultural dentro de la EMEH, y record\u00f3 que la culminaci\u00f3n de estudios profesionales de las y los j\u00f3venes hidalguenses, forma parte de la pol\u00edtica educativa que implementa el gobernador Omar Fayad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ceremonia c\u00edvica encabezada por Ver\u00f3nica Kugel, subsecretaria de Patrimonio y Fomento Cultural, y Aar\u00f3n David Tr\u00e1pala Mart\u00ednez, subdirector acad\u00e9mico de la Escuela de M\u00fasica del Estado de Hidalgo (EMEH) se hizo la entrega de&nbsp; t\u00edtulos profesionales a siete estudiantes de Licenciatura en M\u00fasica e Ingenier\u00eda en Audio. Se inform\u00f3 que en lo que va [&hellip;]<\/p>\n","protected":false},"author":72,"featured_media":192960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,59],"tags":[],"class_list":["post-192947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/192947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=192947"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/192947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/192960"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=192947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=192947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=192947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}