{"id":19038,"date":"2016-03-28T12:34:36","date_gmt":"2016-03-28T12:34:36","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2016\/03\/28\/con-penas-distintas-pero-mexico-condena-a-mujeres-por-abortar\/"},"modified":"2016-03-28T12:34:36","modified_gmt":"2016-03-28T12:34:36","slug":"con-penas-distintas-pero-mexico-condena-a-mujeres-por-abortar","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/con-penas-distintas-pero-mexico-condena-a-mujeres-por-abortar\/","title":{"rendered":"Con penas distintas, pero M\u00e9xico condena a mujeres por abortar"},"content":{"rendered":"<p>En M\u00e9xico el aborto es legal por diversas causales, pero en 29 de las 32 entidades del pa\u00eds se castiga a las mujeres que interrumpan un embarazo con c\u00e1rcel, trabajo a la comunidad, multas econ\u00f3micas y hasta con terapia psicol\u00f3gica. Hasta 2015, 30 segu\u00edan presas por aborto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00a0<\/p>\n<p>De acuerdo con datos del Grupo de Informaci\u00f3n en Reproducci\u00f3n Elegida (GIRE), la interrupci\u00f3n del embarazo se castiga con c\u00e1rcel en 29 estados, en cuatro con trabajo a la comunidad, en 13 con multa econ\u00f3mica, y en seis con tratamiento m\u00e9dico.<\/p>\n<p>En cada estado hay penas distintas: la condena m\u00e1s alta la impone el C\u00f3digo Penal de Sonora, donde el castigo puede ser hasta por seis a\u00f1os de c\u00e1rcel; sin embargo, en Chiapas, Michoac\u00e1n y Veracruz no se priva de la libertad a las mujeres que recurren al procedimiento.<\/p>\n<p>En Veracruz se castigaba con reclusi\u00f3n a las mujeres, pero en 2009 se aprob\u00f3 una reforma para reducir las penas, quitar la c\u00e1rcel y sustituirla por tratamiento psicol\u00f3gico. Aun as\u00ed, en ese estado se castiga con seis meses a dos a\u00f1os de prisi\u00f3n a la persona que asista o ayude a realizar un aborto.<\/p>\n<p>En 2015 en todo el pa\u00eds, 30 mujeres estuvieron encarceladas acusadas del delito de aborto: 15 que ya estaban en prisi\u00f3n y 15 que ingresaron, seg\u00fan datos del Censo Nacional de Gobierno, Seguridad P\u00fablica y Sistema Penitenciario Estatales, que realiza el Instituto Nacional de Geograf\u00eda y Estad\u00edstica (Inegi).<\/p>\n<p>Sobre la penalizaci\u00f3n del aborto, GIRE y otras organizaciones civiles que defienden los derechos reproductivos han se\u00f1alado que esta criminalizaci\u00f3n provoca denuncias contra las mujeres, a pesar de que existen causales que permiten interrumpir un embarazo.<\/p>\n<p>A partir de 2008, luego de que 16 congresos estatales modificaron sus constituciones locales para \u201cproteger la vida desde el momento de la concepci\u00f3n-fecundaci\u00f3n\u201d, GIRE encontr\u00f3 que las denuncias por aborto han ido en aumento.<\/p>\n<p>Para 2015, seg\u00fan el censo del Inegi, ya estaban 15 mujeres recluidas por cometer el delito de aborto, una en Veracruz, una en San Luis Potos\u00ed (SLP), otra en Oaxaca, una m\u00e1s en Nayarit, tres en la Ciudad de M\u00e9xico (donde es legal hasta las 12 semanas de gestaci\u00f3n), y ocho en Sinaloa, \u00e9stas \u00faltimas sentenciadas y las otras todav\u00eda en proceso judicial.<\/p>\n<p>A la par de las sanciones en M\u00e9xico, las 32 entidades permiten el aborto si es producto de una violaci\u00f3n sexual; 30, si fue imprudencial; 23, por peligro de muerte de la mujer; 16, por malformaciones del feto; 14, por razones de salud; 12, por inseminaci\u00f3n artificial no consentida; dos, por razones econ\u00f3micas, y s\u00f3lo en la Ciudad de M\u00e9xico se permite por decisi\u00f3n de las propias mujeres.<\/p>\n<p>En el caso de la capital del pa\u00eds, en 2007 se aprob\u00f3 una reforma para permitir el aborto hasta las 12 semanas de gestaci\u00f3n; pero despu\u00e9s de este periodo, el C\u00f3digo Penal local castiga el delito con penas de tres a seis meses de prisi\u00f3n, y a quien haga abortar a una mujer se le impone de uno a tres a\u00f1os de reclusi\u00f3n.<\/p>\n<p>Esta diversidad normativa hizo que en 2012 el Comit\u00e9 de la Convenci\u00f3n sobre la Eliminaci\u00f3n de Todas las Formas de Discriminaci\u00f3n Contra la Mujer (CEDAW, por sus siglas en ingl\u00e9s) recomendara al Estado mexicano armonizar las leyes, para eliminar los obst\u00e1culos que enfrentan las mujeres que deseen interrumpir su embarazo de forma legal.<\/p>\n<p>En 2015 se sumaron otras 15 mujeres que ingresaron a prisi\u00f3n por este delito: dos en SLP, tres en Tlaxcala, cinco en Jalisco, y en Baja California, Guanajuato, Sonora, Tabasco y Yucat\u00e1n, fue encarcelada una mujer en cada estado, todas acusadas de aborto.<\/p>\n<p>Sin embargo, organizaciones que defienden los derechos femeninos como el Centro Las Libres, en Guanajuato, detectaron que las mujeres que ten\u00edan un aborto, en su mayor\u00eda espont\u00e1neo, eran acusadas y juzgadas por homicidio en raz\u00f3n de parentesco, por lo que podr\u00eda ascender el n\u00famero de reclusas por interrumpir su embarazo. (CIMAC)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En M\u00e9xico el aborto es legal por diversas causales, pero en 29 de las 32 entidades del pa\u00eds se castiga a las mujeres que interrumpan un embarazo con c\u00e1rcel, trabajo a la comunidad, multas econ\u00f3micas y hasta con terapia psicol\u00f3gica. Hasta 2015, 30 segu\u00edan presas por aborto.<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-19038","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/19038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=19038"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/19038\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=19038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=19038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=19038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}