{"id":188442,"date":"2021-10-27T11:41:31","date_gmt":"2021-10-27T16:41:31","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=188442"},"modified":"2021-10-27T11:41:47","modified_gmt":"2021-10-27T16:41:47","slug":"atraparon-a-dos-masculinos-porque-transportaban-mil-litros-de-huachicol","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/atraparon-a-dos-masculinos-porque-transportaban-mil-litros-de-huachicol\/","title":{"rendered":"Atraparon a dos masculinos porque transportaban mil litros de huachicol"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En colaboraci\u00f3n a las acciones que autoridades federales desarrollan para la prevenci\u00f3n y combate al robo de hidrocarburos y la comisi\u00f3n de delitos a trav\u00e9s del uso de armas de fuego, agentes de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo aseguraron a dos individuos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El operativo se desarroll\u00f3 en un camino de terracer\u00eda de la comunidad de Tlaunilolpan, municipio de Chapantongo, donde fue intervenida una camioneta Chevrolet Silverado, pick up, cabina y media, color negro, cargada con un contenedor para mil litros de capacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los tripulantes, que se identificaron como U.N.H., de 27 a\u00f1os, y S.H.R., de 31 a\u00f1os, se les asegur\u00f3 un arma de fuego larga que qued\u00f3 a disposici\u00f3n de la Fiscal\u00eda General de la Rep\u00fablica, mediante su representaci\u00f3n en Hidalgo, al igual que los individuos y la unidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Seguridad P\u00fablica de Hidalgo reitera el llamado a la ciudadan\u00eda para colaborar con estas acciones, realizando reportes mediante el 911 de Emergencias y\/o al 089 de Denuncia An\u00f3nima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En colaboraci\u00f3n a las acciones que autoridades federales desarrollan para la prevenci\u00f3n y combate al robo de hidrocarburos y la comisi\u00f3n de delitos a trav\u00e9s del uso de armas de fuego, agentes de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo aseguraron a dos individuos. El operativo se desarroll\u00f3 en un camino de terracer\u00eda de la [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":188448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-188442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/188442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=188442"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/188442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/188448"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=188442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=188442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=188442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}