{"id":188440,"date":"2021-10-27T11:41:22","date_gmt":"2021-10-27T16:41:22","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=188440"},"modified":"2021-10-27T11:41:36","modified_gmt":"2021-10-27T16:41:36","slug":"asegura-policia-estatal-a-individuo-con-armas-en-singuilucan","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/asegura-policia-estatal-a-individuo-con-armas-en-singuilucan\/","title":{"rendered":"Asegura Polic\u00eda Estatal a individuo con armas en Singuilucan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mediante la realizaci\u00f3n de tareas de prevenci\u00f3n y vigilancia, elementos dependientes de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo, durante las \u00faltimas horas aseguraron a un hombre que trasladaba armas de fuego, de las que no pudo acreditar su posesi\u00f3n legal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la expedici\u00f3n de un comunicado oficial, la dependencia que comanda Mauricio Delmar Saavedra dio a conocer que fue a la altura de la localidad de El Susto del municipio de Singuilucan, sobre la carretera Pachuca-Tulancingo, donde agentes estatales intervinieron un auto Volkswagen Jetta, color blanco, con placas de circulaci\u00f3n del estado de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al conductor, que se identific\u00f3 como E.H.J., quien manifest\u00f3 contar con 37 a\u00f1os de edad, le fueron aseguradas dos armas de fuego calibres .22 y .380, por lo que fue detenido y consignado ante la Fiscal\u00eda General de la Rep\u00fablica, a trav\u00e9s de la carpeta de investigaci\u00f3n correspondiente, para definir su situaci\u00f3n jur\u00eddica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RECUPERAN POLIC\u00cdAS ESTATALES CAMIONETA ROBADA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otra intervenci\u00f3n policial, mediante acciones de reacci\u00f3n inmediata, agentes de la Polic\u00eda del Estado lograron la recuperaci\u00f3n de una camioneta que hab\u00eda sido reportada como robada en la ciudad de Tulancingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oficiales avistaron el veh\u00edculo marca Dodge Ram, color blanco, con plataforma, en la carretera Tulancingo-Metepec, y con ello pudieron asegurar y recuperar la unidad a la altura del lugar conocido Las Hornillas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El autom\u00f3vil fue robado sobre la carretera federal M\u00e9xico-Tuxpan, a la altura del crucero de Acatl\u00e1n, donde se emiti\u00f3 el reporte de robo a trav\u00e9s del C5i, que activ\u00f3 protocolos de b\u00fasqueda en la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Seguridad P\u00fablica de Hidalgo reitera el llamado a la ciudadan\u00eda para colaborar con estas acciones, realizando reportes mediante el 911 de Emergencias y\/o al 089 de Denuncia An\u00f3nima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante la realizaci\u00f3n de tareas de prevenci\u00f3n y vigilancia, elementos dependientes de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo, durante las \u00faltimas horas aseguraron a un hombre que trasladaba armas de fuego, de las que no pudo acreditar su posesi\u00f3n legal. Con la expedici\u00f3n de un comunicado oficial, la dependencia que comanda Mauricio Delmar Saavedra [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":188446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-188440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/188440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=188440"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/188440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/188446"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=188440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=188440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=188440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}