{"id":188435,"date":"2021-10-27T09:18:03","date_gmt":"2021-10-27T14:18:03","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=188435"},"modified":"2021-10-27T09:18:15","modified_gmt":"2021-10-27T14:18:15","slug":"amlo-acusa-al-supremo-de-proteger-corrupcion-y-a-la-minoria","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/amlo-acusa-al-supremo-de-proteger-corrupcion-y-a-la-minoria\/","title":{"rendered":"AMLO acusa al Supremo de &#8220;proteger corrupci\u00f3n y a la minor\u00eda&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EFE.- AMLO acus\u00f3 ayer a la Suprema Corte de &#8220;proteger la corrupci\u00f3n&#8221; y &#8220;a la minor\u00eda&#8221;. Critic\u00f3 a los ministros de la Corte por invalidar la reforma que impuls\u00f3 su Gobierno para establecer prisi\u00f3n preventiva obligatoria, es decir autom\u00e1tica, para delitos relacionados con defraudaci\u00f3n fiscal, contrabando y venta de facturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;NO TENGO NADA CONTRA ROBLES, YO NO ODIO A NADIE\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de que Rosario Robles, exsecretaria de Desarrollo Social en el sexenio pasado, declar\u00f3 en entrevista con H\u00e9ctor de Maule\u00f3n que es presa pol\u00edtica, adem\u00e1s que le pidieron inculpar a Enrique Pe\u00f1a Nieto y a Luis Videgaray, AMLO afirm\u00f3 que &#8220;no es mi fuerte la venganza y no odio a nadie&#8221;. Rechaz\u00f3 que haya una venganza pol\u00edtica en contra de Rosario Robles Berlanga, quien est\u00e1 recluida en el penal de Santa Martha Acatitla, acusada por presuntos actos de corrupci\u00f3n en el caso de la &#8220;Estafa Maestra&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;DINAMARCA ES MI MODELO PORQUE NO HAY CORRUPCI\u00d3N\u201d&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de que un experto de Bloomberg gener\u00f3 controversia al decir que M\u00e9xico podr\u00eda ser \u201cla pr\u00f3xima Dinamarca\u201d, AMLO asegur\u00f3 que ese pa\u00eds es modelo a seguir, \u201cEn ella no existe la corrupci\u00f3n ni la pobreza, \u201cha instaurado un Estado de Bienestar\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;\u201cLA ALCALDESA DE CUAUHT\u00c9MOC SAC\u00d3 EL COBRE\u201d<\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AMLO hizo referencia a una entrevista que Carlos Alazraki tuvo con Sandra Cuevas, quien extern\u00f3 que no le gustan los pobres. \u201cEsto es lo que est\u00e1 saliendo, esto exist\u00eda (&#8230;) Todo esto se ocultaba, el racismo, el clasismo y ahora est\u00e1 saliendo\u201d, extern\u00f3 AMLO. \u201cTodo esto es bueno que salga, porque la verdad est\u00e1n mostrando el cobre&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EFE.- AMLO acus\u00f3 ayer a la Suprema Corte de &#8220;proteger la corrupci\u00f3n&#8221; y &#8220;a la minor\u00eda&#8221;. Critic\u00f3 a los ministros de la Corte por invalidar la reforma que impuls\u00f3 su Gobierno para establecer prisi\u00f3n preventiva obligatoria, es decir autom\u00e1tica, para delitos relacionados con defraudaci\u00f3n fiscal, contrabando y venta de facturas. &#8220;NO TENGO NADA CONTRA ROBLES, [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":187536,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-188435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/188435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=188435"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/188435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/187536"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=188435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=188435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=188435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}