{"id":186402,"date":"2021-10-13T16:09:43","date_gmt":"2021-10-13T21:09:43","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=186402"},"modified":"2021-10-13T16:09:58","modified_gmt":"2021-10-13T21:09:58","slug":"deportados-mas-de-41-000-hondurenos-en-2021","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/deportados-mas-de-41-000-hondurenos-en-2021\/","title":{"rendered":"Deportados m\u00e1s de 41.000 hondure\u00f1os en 2021"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">(EFE) Un total de 41.362 hondure\u00f1os indocumentados han sido deportados desde M\u00e9xico, Estados Unidos y Centroam\u00e9rica en lo que va de a\u00f1o, inform\u00f3 este mi\u00e9rcoles el Observatorio Consular y Migratorio de Honduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 87,9 % de los hondure\u00f1os retornados provienen de M\u00e9xico, un 10,8 % de Estados Unidos y el 1,3 % fue regresado de pa\u00edses de Centroam\u00e9rica tras su intento de llegar a EE.UU., seg\u00fan un informe del Observatorio Consular, al que Efe tuvo acceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades migratorias de Estados Unidos han deportado a Honduras a 4.459 personas, entre ellas 606 menores de edad, algunos no acompa\u00f1ados, a\u00f1aden las estad\u00edsticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico retorn\u00f3 al pa\u00eds centroamericano, por v\u00eda a\u00e9rea, a 5.898 migrantes hondure\u00f1os indocumentados, incluidos 1.484 menores de edad, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros 30.479 hondure\u00f1os fueron deportados tambi\u00e9n por las autoridades mexicanas v\u00eda terrestre, mientras que 525 fueron repatriadas desde pa\u00edses de Centroam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un hondure\u00f1o adulto fue deportado desde un pa\u00eds de Europa, no identificado por el Observatorio Consular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del total de deportados, 36.437 eran adultos, es decir 32.238 hombres y 4.199 mujeres. Los menores de edad retornados en el periodo de an\u00e1lisis sumaron 4.925 y representan el 11,9 % del total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los menores que cada a\u00f1o intentan llegar a Estados Unidos, seg\u00fan organismos de derechos humanos, lo hacen con la idea de reencontrarse con familiares y por la violencia que sufre el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hondure\u00f1os retornados son atendidos en los Centros de Atenci\u00f3n al Migrante Retornado (CAMR) ubicados en San Pedro Sula y Omoa, en el norte y Caribe del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un total de 36.588 hondure\u00f1os fueron deportados al pa\u00eds centroamericano en todo 2020, la menor cifra desde 2017, con una disminuci\u00f3n de 66,5 % respecto al 2019 (109.185), seg\u00fan el Observatorio Consular y Migratorio de Honduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alrededor de un mill\u00f3n de hondure\u00f1os, entre residentes legales e indocumentados, viven en Estados Unidos luego de escapar de situaciones que afectan a su pa\u00eds como la violencia y la pobreza, seg\u00fan autoridades de Tegucigalpa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los que viven en el exterior, principalmente en EE.UU. y Espa\u00f1a, env\u00edan remesas familiares, las que al a\u00f1o superan los 4.000 millones de d\u00f3lares, seg\u00fan cifras del Banco Central de Honduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 95,3 % de las remesas familiares enviadas a Honduras este a\u00f1o por inmigrantes del pa\u00eds proviene de Estados Unidos y un 2,8 % lleg\u00f3 desde Espa\u00f1a, de acuerdo a un informe del emisor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La recepci\u00f3n de remesas familiares en Honduras se remonta a la emigraci\u00f3n masiva de hondure\u00f1os tras el devastador paso del hurac\u00e1n Mitch por Centroam\u00e9rica a finales de 1998.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las remesas se han constituido en uno de los principales sustentos de muchas familias de Honduras y en una fuente importante de divisas de este pa\u00eds, por encima de las exportaciones como el caf\u00e9, los productos de la maquila, el camar\u00f3n y otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EFE) Un total de 41.362 hondure\u00f1os indocumentados han sido deportados desde M\u00e9xico, Estados Unidos y Centroam\u00e9rica en lo que va de a\u00f1o, inform\u00f3 este mi\u00e9rcoles el Observatorio Consular y Migratorio de Honduras. El 87,9 % de los hondure\u00f1os retornados provienen de M\u00e9xico, un 10,8 % de Estados Unidos y el 1,3 % fue regresado de [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":186404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-186402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/186402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=186402"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/186402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/186404"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=186402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=186402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=186402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}