{"id":184782,"date":"2021-10-02T08:53:13","date_gmt":"2021-10-02T13:53:13","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=184782"},"modified":"2021-10-02T08:53:26","modified_gmt":"2021-10-02T13:53:26","slug":"alcalde-gestiona-en-el-congreso-local-recursos-adicionales","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/alcalde-gestiona-en-el-congreso-local-recursos-adicionales\/","title":{"rendered":"Alcalde gestiona en el Congreso Local recursos adicionales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Tula de Allende<\/strong>.- El presidente municipal de Tula de Allende, Manuel Hern\u00e1ndez Badillo, acudi\u00f3 el pasado jueves al Congreso del estado de Hidalgo, para gestionar recursos adicionales que permitan aliviar la grave situaci\u00f3n de miles de personas que resultaron afectadas por la inundaci\u00f3n del 6 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alcalde tulense, fue recibido por una comisi\u00f3n de legisladores encabezados por Julio Valera Piedras, presidente de la mesa directiva del mes de septiembre, en la sexag\u00e9sima cuarta legislatura local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe del Ejecutivo municipal, Manuel Hern\u00e1ndez Badillo, subray\u00f3 que es urgente contar con un recurso adicional para atender a los damnificados y la estructura urbana y, particularmente, para mejorar el drenaje ya que ahora se encuentra colapsado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al apelar a la solidaridad de los legisladores hidalguenses, el alcalde solicit\u00f3 que de manera inmediata y especialmente en el presupuesto que se apruebe para 2022 debe considerarse la tragedia que para el municipio represent\u00f3 el desbordamiento de los r\u00edos Tula y Rosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expuso que cientos de familias lo perdieron todo, al igual que comerciantes y hoy esa debe ser la prioridad de los distintos \u00f3rdenes de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El prop\u00f3sito com\u00fan de autoridades, legisladores y ciudadanos es tender la mano a los damnificados&#8221;, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subray\u00f3, ante los legisladores hidalguenses que su administraci\u00f3n se est\u00e1 conduciendo por causas institucionales para poder atender esa gran problem\u00e1tica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hemos sido muy enf\u00e1ticos en que ahora no debe haber colores partidistas ni intentos por sacar provecho de esta desgracia para evitar exacerbar \u00e1nimos&#8221;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1ndez Badillo insisti\u00f3 en su llamado a la unidad, al di\u00e1logo y al respeto a la pol\u00edtica para salir adelante de esta situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Trabajemos en unidad y busquemos el bienestar de los tulenses pues s\u00f3lo con trabajo y empat\u00eda lograremos consolidar a Tula, como el municipio de guerreros toltecas&#8221;, manifest\u00f3 el alcalde, quien en su visita al Congreso estuvo acompa\u00f1ado por integrantes de la H. Asamblea de Tula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale se\u00f1alar que con el prop\u00f3sito de gestionar apoyos y recursos que permitan atender la tragedia en Tula el presidente municipal tambi\u00e9n ha acudido al Palacio Legislativo de San L\u00e1zaro y al Senado de la Rep\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tula de Allende.- El presidente municipal de Tula de Allende, Manuel Hern\u00e1ndez Badillo, acudi\u00f3 el pasado jueves al Congreso del estado de Hidalgo, para gestionar recursos adicionales que permitan aliviar la grave situaci\u00f3n de miles de personas que resultaron afectadas por la inundaci\u00f3n del 6 de septiembre. El alcalde tulense, fue recibido por una comisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":184788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2159,40],"tags":[],"class_list":["post-184782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/184782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=184782"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/184782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/184788"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=184782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=184782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=184782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}