{"id":182593,"date":"2021-09-18T06:00:00","date_gmt":"2021-09-18T11:00:00","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=182593"},"modified":"2021-09-18T11:50:39","modified_gmt":"2021-09-18T16:50:39","slug":"exigen-delimitar-zona-arqueologica-en-huapalcalco","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/exigen-delimitar-zona-arqueologica-en-huapalcalco\/","title":{"rendered":"Exigen delimitar zona arqueol\u00f3gica en Huapalcalco"},"content":{"rendered":"\n<p><strong>Tulancingo<\/strong>.- El Instituto Nacional de Antropolog\u00eda e Historia (INAH) ha solicitado que entre en etapa de revisi\u00f3n de un tribunal colegiado, la solicitud de declaratoria como zona de monumentos arqueol\u00f3gicos para Huapalcalco que promueve la sociedad civil.<\/p>\n\n\n\n<p>Pidi\u00f3 tambi\u00e9n al alcalde de Tulancingo, Jorge M\u00e1rquez, les ayude a conseguir en donaci\u00f3n 20 hect\u00e1reas de terreno.<\/p>\n\n\n\n<p>En conferencia de prensa, miembros de las asociaci\u00f3n civil Niebla y Tiempo, solicitaron al edil conteste a la brevedad si es factible o no.<\/p>\n\n\n\n<p>Montserrat Barrag\u00e1n y Alejandro Aldana, integrantes de dicha asociaci\u00f3n, informaron que conforme a la Ley de Transparencia, solicitaron a la delegaci\u00f3n en Hidalgo del INAH y a la Coordinaci\u00f3n Nacional de Arqueolog\u00eda, les permitiera revisar el expediente t\u00e9cnico respecto a la declaratoria de Huapalcalco como zona arqueol\u00f3gica.<\/p>\n\n\n\n<p>En respuesta, la delegaci\u00f3n estatal del INAH se\u00f1al\u00f3 que no pod\u00edan dar informaci\u00f3n, pero la Coordinaci\u00f3n Nacional de Arqueolog\u00eda autoriz\u00f3 que fueran a la CDMX a revisar el expediente y fotografiar.<\/p>\n\n\n\n<p>En esa revisi\u00f3n los activistas encontraron dos propuestas de poligonal, una de las cuales abarca 11 hect\u00e1reas y toda la franja urbanizada de las colonias San Jos\u00e9 Caltengo y Huapalcalco queda fuera de la poligonal.<\/p>\n\n\n\n<p>\u201cEso es un avance porque desde hace a\u00f1os hemos dicho que no se trata de despojar de sus viviendas a la gente de Huapalcalco y si alguno de esos predios ten\u00eda que ser parte de la poligonal, siempre buscamos que se les pagara como se debe\u201d, coment\u00f3 Barrag\u00e1n.<\/p>\n\n\n\n<p>Esa franja urbanizada mide aproximadamente nueve hect\u00e1reas; las cuales ya se desprenden de las dos propuestas de poligonal y se respeta la propiedad de los habitantes de Huapalcalco que por d\u00e9cadas han trabajado por ella.<\/p>\n\n\n\n<p>Informaron que en esa franja hay 180 propietarios, quienes cuentan con un n\u00famero catastral y el 70 por ciento tienen sus escrituras en orden, pues ya est\u00e1 urbanizado y tienen todos los servicios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tulancingo.- El Instituto Nacional de Antropolog\u00eda e Historia (INAH) ha solicitado que entre en etapa de revisi\u00f3n de un tribunal colegiado, la solicitud de declaratoria como zona de monumentos arqueol\u00f3gicos para Huapalcalco que promueve la sociedad civil. Pidi\u00f3 tambi\u00e9n al alcalde de Tulancingo, Jorge M\u00e1rquez, les ayude a conseguir en donaci\u00f3n 20 hect\u00e1reas de terreno. [&hellip;]<\/p>\n","protected":false},"author":70,"featured_media":182603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2159,40],"tags":[],"class_list":["post-182593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/182593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=182593"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/182593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/182603"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=182593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=182593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=182593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}