{"id":180369,"date":"2021-09-03T18:52:57","date_gmt":"2021-09-03T23:52:57","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=180369"},"modified":"2021-09-03T18:59:55","modified_gmt":"2021-09-03T23:59:55","slug":"lxiv-legislatura-convoca-al-noveno-periodo-ordinario-de-sesiones","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/lxiv-legislatura-convoca-al-noveno-periodo-ordinario-de-sesiones\/","title":{"rendered":"LXIV LEGISLATURA CONVOCA AL NOVENO PERIODO ORDINARIO DE SESIONES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este viernes 3 de septiembre, se llev\u00f3 a cabo la sesi\u00f3n n\u00famero 47 de la Diputaci\u00f3n Permanente de esta LXIV Legislatura del Congreso del Estado de Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante estos trabajos, se present\u00f3 la iniciativa a cargo del Diputado V\u00edctor Osmind Guerrero Trejo, la cual propone reformar el art\u00edculo 125 de la Ley Org\u00e1nica del Poder Legislativo del Estado Libre y Soberano de Hidalgo, con la finalidad de fortalecer y clarificar los requisitos con los que se debe integrar una iniciativa a efecto de que, para su an\u00e1lisis y estudio en la Comisi\u00f3n Legislativa a la que haya sido enviada sea m\u00e1s \u00e1gil y exponga claramente la idea que el legislador promovente quiera expresar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, en esta sesi\u00f3n, se present\u00f3 para su aprobaci\u00f3n, el acuerdo para convocar al noveno periodo extraordinario de sesiones de esta LXIV Legislatura, emitido por la Diputaci\u00f3n Permanente de esta soberan\u00eda dicho acuerdo fue aprobado con 9 votos a favor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se present\u00f3 el informe sobre el estado que guardan los expedientes turnados a la Primera Comisi\u00f3n Permanente de Cultura del Congreso del Estado de Hidalgo, lo anterior a cargo de la Diputada Mar\u00eda Corina Mart\u00ednez Garc\u00eda; en la cual destac\u00f3 a su comisi\u00f3n, como la m\u00e1s importante de esta Legislatura y expres\u00f3 el agradecimiento a quienes apoyaron los temas en materia de cultura en la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otra participaci\u00f3n, el Diputado V\u00edctor Osmind Guerrero Trejo, present\u00f3 el informe de la Comisi\u00f3n de Seguridad Ciudadana y Justicia de esta LXIV Legislatura. Mencion\u00f3 la realizaci\u00f3n de reuniones institucionales con distintas dependencias y \u00f3rganos de seguridad y justicia a nivel local y federal. Expres\u00f3 que la comisi\u00f3n que presidi\u00f3, queda en ceros, en lo referente a temas turnados a la comisi\u00f3n; se reform\u00f3 el c\u00f3digo penal, la homologaci\u00f3n del n\u00famero 911, se tipific\u00f3 la violencia digital; se armoniz\u00f3 la legislaci\u00f3n local para homologar el delito de desaparici\u00f3n forzada; se tipific\u00f3 el delito de falsificaci\u00f3n de documentos, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro orden de ideas, se procedi\u00f3 a la elecci\u00f3n de la mesa directiva que habr\u00e1 de conducir los trabajos de la sesi\u00f3n correspondiente al noveno periodo ordinario de sesiones, la cual qued\u00f3 conformada de la siguiente manera:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Humberto Augusto Veras Godoy Presidente, Mar\u00eda Luisa P\u00e9rez Perusqu\u00eda Vicepresidente, Jorge Mayorga Olvera Secretario 1, Ricardo Ra\u00fal Baptista Secretario 2, Armando Quintanar Trejo Suplente, Rafael Garnica Alonso Suplente 2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez concluidos los trabajos de la presente sesi\u00f3n de la Diputaci\u00f3n Permanente, se convoc\u00f3 a los integrantes de la LXIV Legislatura a la sesi\u00f3n del noveno periodo extraordinario, la cual se llevar\u00e1 a cabo este d\u00eda viernes 3 de septiembre a partir de las 17:00 horas en el sal\u00f3n de plenos del Congreso del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes 3 de septiembre, se llev\u00f3 a cabo la sesi\u00f3n n\u00famero 47 de la Diputaci\u00f3n Permanente de esta LXIV Legislatura del Congreso del Estado de Hidalgo. Durante estos trabajos, se present\u00f3 la iniciativa a cargo del Diputado V\u00edctor Osmind Guerrero Trejo, la cual propone reformar el art\u00edculo 125 de la Ley Org\u00e1nica del Poder [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":180371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,2159,1],"tags":[],"class_list":["post-180369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-noticias-de-hidalgo","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/180369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=180369"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/180369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/180371"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=180369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=180369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=180369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}