{"id":180052,"date":"2021-09-01T17:34:11","date_gmt":"2021-09-01T22:34:11","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=180052"},"modified":"2021-09-01T17:34:56","modified_gmt":"2021-09-01T22:34:56","slug":"detienen-a-pareja-que-transportaba-hidrocarburo-presuntamente-robado","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/detienen-a-pareja-que-transportaba-hidrocarburo-presuntamente-robado\/","title":{"rendered":"Detienen a pareja que transportaba hidrocarburo presuntamente robado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Tulancingo de Bravo, Hgo.-<\/strong> La tarde del pasado martes 31 de agosto, la Secretar\u00eda de Seguridad Ciudadana de Tulancingo realiz\u00f3 la detenci\u00f3n de una mujer y un hombre por su probable participaci\u00f3n en el trasiego de combustible de dudosa procedencia, en Tulancingo, Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con informaci\u00f3n oficial, elementos de Seguridad P\u00fablica realizaban recorridos de vigilancia sobre el Circuito Chapultepec y se percataron que una unidad automotriz iba circulando de manera imprudente sobre la mencionada vialidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tal motivo, los elementos le marcaron el alto al conductor e intervinieron para realizar una inspecci\u00f3n, localizando al interior del veh\u00edculo, ocho garrafones con capacidad de 50 litros, abastecidos a un 90 por ciento de su capacidad con l\u00edquido con caracter\u00edsticas similares al hidrocarburo, haciendo un total aproximado de 400 litros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo anterior, fueron detenidos una mujer y un hombre que ven\u00edan a cargo de la unidad vehicular y puestos a disposici\u00f3n de la Fiscal\u00eda General de la Rep\u00fablica para su tr\u00e1mite correspondiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tulancingo de Bravo, Hgo.- La tarde del pasado martes 31 de agosto, la Secretar\u00eda de Seguridad Ciudadana de Tulancingo realiz\u00f3 la detenci\u00f3n de una mujer y un hombre por su probable participaci\u00f3n en el trasiego de combustible de dudosa procedencia, en Tulancingo, Hidalgo. De acuerdo con informaci\u00f3n oficial, elementos de Seguridad P\u00fablica realizaban recorridos de [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":180054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,2159,40],"tags":[],"class_list":["post-180052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/180052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=180052"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/180052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/180054"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=180052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=180052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=180052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}