{"id":168163,"date":"2021-06-16T11:00:48","date_gmt":"2021-06-16T16:00:48","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=168163"},"modified":"2021-06-16T11:01:06","modified_gmt":"2021-06-16T16:01:06","slug":"protestas-contra-la-marcha-de-la-bandera-israeli","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/protestas-contra-la-marcha-de-la-bandera-israeli\/","title":{"rendered":"Protestas contra la marcha de la bandera israel\u00ed"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EFE.- Alrededor de un millar de palestinos se unieron a las protestas a lo largo de la zona fronteriza entre la Franja de Gaza e Israel contra la &#8220;Marcha de las Banderas&#8221;, un desfile de ultranacionalistas israel\u00edes que se celebr\u00f3 ayer por las calles de Jerusal\u00e9n y es visto como una provocaci\u00f3n por los palestinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes de seguridad palestinas y testigos presenciales indicaron que la mayor\u00eda de las protestas tuvieron lugar cerca de la valla fronteriza al este de la ciudad de Khan Younis, en el sur de la Franja, y en la zona norte de la ciudad de Beit Hanoun, en el norte del enclave costero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los testigos contaron que soldados israel\u00edes apostados en la zona fronteriza abrieron cartuchos de gas lacrim\u00f3geno y munici\u00f3n real para dispersar a los manifestantes que se acercaban a la valla de la frontera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Activistas palestinos anunciaron en un comunicado que organizar\u00e1n protestas nocturnas cerca de la frontera con Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las manifestaciones en Gaza son una protesta a la Marcha de las Banderas, que reivindica la soberan\u00eda israel\u00ed sobre la Ciudad Santa ya que conmemora lo que los israel\u00edes consideran la reunificaci\u00f3n de la urbe en 1967, que para los palestinos marca el inicio de la ocupaci\u00f3n en Jerusal\u00e9n Este, por donde circul\u00f3 la mayor parte del desfile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EFE.- Alrededor de un millar de palestinos se unieron a las protestas a lo largo de la zona fronteriza entre la Franja de Gaza e Israel contra la &#8220;Marcha de las Banderas&#8221;, un desfile de ultranacionalistas israel\u00edes que se celebr\u00f3 ayer por las calles de Jerusal\u00e9n y es visto como una provocaci\u00f3n por los palestinos. [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":168164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-168163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/168163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=168163"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/168163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/168164"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=168163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=168163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=168163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}