{"id":167728,"date":"2021-06-12T15:49:06","date_gmt":"2021-06-12T20:49:06","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=167728"},"modified":"2021-06-12T15:49:21","modified_gmt":"2021-06-12T20:49:21","slug":"ong-piden-al-gobierno-una-estrategia-para-frenar-el-trabajo-infantil","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/ong-piden-al-gobierno-una-estrategia-para-frenar-el-trabajo-infantil\/","title":{"rendered":"ONG piden al Gobierno una estrategia para frenar el trabajo infantil"},"content":{"rendered":"\n<p>Organizaciones internacionales hicieron este s\u00e1bado un llamado urgente a que el Gobierno mexicano dise\u00f1e una estrategia nacional para prevenir, atender y erradicar el trabajo infantil.<\/p>\n\n\n\n<p>&#8220;Un llamado urgente para que se dise\u00f1e una Estrategia Nacional que incluya programas y pol\u00edticas sectoriales con acciones espec\u00edficas para prevenir, atender y erradicar el trabajo infantil&#8221;, expresaron en un comunicado conjunto las organizaciones World Vision M\u00e9xico y Save The Children.<\/p>\n\n\n\n<p>En el marco del D\u00eda Mundial contra el Trabajo Infantil, que se conmemora este 12 de junio, exaltaron la necesidad de una estrategia que incluya programas y pol\u00edticas sectoriales con acciones espec\u00edficas.<\/p>\n\n\n\n<p>Las organizaciones indicaron que dicha estrategia deber\u00e1 contemplarse en el presupuesto federal, asegurando los recursos suficientes para su implementaci\u00f3n.<\/p>\n\n\n\n<p>A nivel mundial, expresaron, el trabajo infantil afecta el presente y futuro de 152 millones de ni\u00f1as, ni\u00f1os y adolescentes.<\/p>\n\n\n\n<p>De acuerdo con la Encuesta Nacional de Trabajo Infantil (ENTI) 2019, hay 3,3 millones de menores vinculados a este tipo de labores.<\/p>\n\n\n\n<p>De esos 3,3 millones, 600.000 ponen en peligro sus vidas al trabajar diariamente en los campos agr\u00edcolas.<\/p>\n\n\n\n<p>Mientras que las v\u00edctimas m\u00e1s vulnerables son las que pertenecen a comunidades ind\u00edgenas, afrodescendientes y\/o con alguna discapacidad.<\/p>\n\n\n\n<p><strong>AFECTACIONES POR PANDEMIA<\/strong><\/p>\n\n\n\n<p>Para World Vision M\u00e9xico, es probable que la pandemia por covid-19 haya aumentado las cifras de trabajo infantil.<\/p>\n\n\n\n<p>De acuerdo con la Comisi\u00f3n Econ\u00f3mica para Am\u00e9rica Latina y el Caribe (Cepal), durante la pandemia, en M\u00e9xico 628.000 de ni\u00f1os y adolescentes abandonaron sus estudios.<\/p>\n\n\n\n<p>Esto debido a la crisis econ\u00f3mica, la falta de ingresos familiares suficientes y ausencia de condiciones para continuar estudiando a distancia.<\/p>\n\n\n\n<p>Oscar Castillo, director del Programa Campos de Esperanza en la organizaci\u00f3n World Vision, se deben establecer medidas efectivas e inmediatas para abolir el trabajo infantil.<\/p>\n\n\n\n<p>&#8220;Se deben de construir consensos para la consolidaci\u00f3n de alianzas entre el gobierno, sociedad civil, sector privado y organizaciones de trabajadores para prevenirlo y erradicarlo&#8221;, indic\u00f3.<\/p>\n\n\n\n<p>Ambas organizaciones expresaron que se debe seguir promoviendo el trabajo digno o decente, junto con la defensa y protecci\u00f3n de los derechos laborales, ya que permite que las familias tengan los recursos necesarios para vivir dignamente y no recurran al trabajo infantil.<\/p>\n\n\n\n<p>Agregaron que las acciones emprendidas para prevenir y erradicar el trabajo infantil tienen que enfocarse en los sectores con mayor prevalencia, como la agricultura.<\/p>\n\n\n\n<p>Expresaron que se debe prestar especial atenci\u00f3n a las necesidades de las familias jornaleras migrantes, provenientes de comunidades ind\u00edgenas, y con acciones diferenciadas para abordar las vulneraciones de derechos que afectan a las mujeres.<\/p>\n\n\n\n<p>Por su parte, Save The Children insisti\u00f3 en la necesidad de que el Gobierno, empresas y sociedad civil tomen acciones para reducir el trabajo infantil.<\/p>\n\n\n\n<p>&#8220;Sobre todo ahora, que la pobreza, empleo informal y desempleo generados por la pandemia amenazan con incrementar exponencialmente el n\u00famero de ni\u00f1as y ni\u00f1os en actividades productivas&#8221;, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizaciones internacionales hicieron este s\u00e1bado un llamado urgente a que el Gobierno mexicano dise\u00f1e una estrategia nacional para prevenir, atender y erradicar el trabajo infantil. &#8220;Un llamado urgente para que se dise\u00f1e una Estrategia Nacional que incluya programas y pol\u00edticas sectoriales con acciones espec\u00edficas para prevenir, atender y erradicar el trabajo infantil&#8221;, expresaron en un [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":167729,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36],"tags":[],"class_list":["post-167728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/167728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=167728"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/167728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/167729"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=167728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=167728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=167728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}