{"id":154419,"date":"2021-02-26T23:28:37","date_gmt":"2021-02-27T05:28:37","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=154419"},"modified":"2021-02-26T23:28:48","modified_gmt":"2021-02-27T05:28:48","slug":"hayek-presentara-los-globos-de-oro","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/hayek-presentara-los-globos-de-oro\/","title":{"rendered":"Hayek presentar\u00e1 los Globos de Oro"},"content":{"rendered":"\n<p>Salma Hayek figura entre los \u00faltimos fichajes para la lista de presentadores de la 78 edici\u00f3n de los Globos de Oro, que se retras\u00f3 dos meses debido a la pandemia y que se celebrar\u00e1 el pr\u00f3ximo domingo con una gala en gran medida virtual.<\/p>\n\n\n\n<p>La Asociaci\u00f3n de la Prensa Extranjera de Hollywood (HFPA), que organiza cada a\u00f1o estos galardones, dio a conocer este jueves en Twitter una nueva relaci\u00f3n de estrellas que participar\u00e1n en la ceremonia desvelando los nombres de los ganadores.<\/p>\n\n\n\n<p>La HFPA tambi\u00e9n incluy\u00f3 entre sus nuevas incorporaciones a Laura Dern, Jamie Lee Curtis y Angela Bassett.<\/p>\n\n\n\n<p>Estas cuatro artistas se unen a las figuras de Hollywood ya anunciadas para los Globos de Oro en los \u00faltimos d\u00edas: Joaquin Phoenix, Ren\u00e9e Zellweger, Awkwafina, Cynthia Erivo, Kristen Wiig, Annie Mumolo, Margot Robbie, Michael Douglas, Catherine Zeta-Jones, Kevin Bacon, Kyra Sedgwick, Anthony Anderson, Tiffany Haddish, Kenan Thompson, Kate Hudson, Sterling K. Brown, Susan Kelechi Watson, Rosie P\u00e9rez, Bryce Dallas Howard, Christian Slater y Chris Meloni.<\/p>\n\n\n\n<p>Amy Poehler y Tina Fey, desde Los \u00c1ngeles y Nueva York, respectivamente, ser\u00e1n las maestras de ceremonias de estos Globos de Oro muy singulares debido a la crisis del coronavirus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salma Hayek figura entre los \u00faltimos fichajes para la lista de presentadores de la 78 edici\u00f3n de los Globos de Oro, que se retras\u00f3 dos meses debido a la pandemia y que se celebrar\u00e1 el pr\u00f3ximo domingo con una gala en gran medida virtual. La Asociaci\u00f3n de la Prensa Extranjera de Hollywood (HFPA), que organiza [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":154421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-154419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/154419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=154419"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/154419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/154421"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=154419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=154419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=154419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}