{"id":147709,"date":"2021-01-08T12:24:06","date_gmt":"2021-01-08T18:24:06","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=147709"},"modified":"2021-01-08T12:24:21","modified_gmt":"2021-01-08T18:24:21","slug":"puebla-y-chivas-buscan-sus-primeros-tres-puntos","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/puebla-y-chivas-buscan-sus-primeros-tres-puntos\/","title":{"rendered":"Puebla y Chivas buscan sus primeros tres puntos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a0(EL UNIVERSAL).- El Puebla a las Chivas Rayadas del Guadalajara en el estadio Cuauht\u00e9moc dentro de la jornada 1 del Torneo Guard1anes 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Franja busca igualar la proeza del torneo pasado y clasificarse nuevamente a la liguilla aunque comenzar\u00e1 el a\u00f1o con nueve bajas, que incluyen a su exdirector t\u00e9cnico, Juan Reynoso, quien ahora dirige al Cruz Azul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la mano de Nicol\u00e1s Lacarm\u00f3n, los camoteros tendr\u00e1n dentro de su alineaci\u00f3n a Anthony Silva, Daniel Segura, Clyffor Aboagye, Guillermo Mart\u00ednez, Diego de Buen, Juan Pablo Segovia y Lumas Maia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, los dirigidos por &#8220;El Rey Midas&#8221; buscar\u00e1n llegar a la final del Guardianes 2021, toda vez que en el torneo pasado fueron eliminados en semifinales por el Le\u00f3n, actual campe\u00f3n del balompi\u00e9 mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9sar Huerta, quien est\u00e1 de vuelta con los rojiblancos luego de su pr\u00e9stamo con el Mazatl\u00e1n, afirm\u00f3 que en el Chiver\u00edo &#8220;juegan los mejores mexicanos&#8221; por lo que est\u00e1 ilusionado de hacer un buen trabajo y ganarse un lugar en la escuadra dirigida por V\u00edctor Manuel Vucetich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima ocasi\u00f3n que se enfrentaron ambas oncenas, los poblanos sacaron la victoria de visitante por la m\u00ednima diferencia; sin embargo, en los \u00faltimos cinco torneos, los rojiblancos apenas han rescatado dos empates: en el Apertura 2019 y Apertura 2018; el resto de los encuentros, el Puebla se ha alzado con el triunfo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El partido se disputar hoy, en punto de las 21:30 hora centro y se transmitir\u00e1 por televisi\u00f3n abierta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0(EL UNIVERSAL).- El Puebla a las Chivas Rayadas del Guadalajara en el estadio Cuauht\u00e9moc dentro de la jornada 1 del Torneo Guard1anes 2021. La Franja busca igualar la proeza del torneo pasado y clasificarse nuevamente a la liguilla aunque comenzar\u00e1 el a\u00f1o con nueve bajas, que incluyen a su exdirector t\u00e9cnico, Juan Reynoso, quien ahora [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":147717,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-147709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportiva"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/147709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=147709"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/147709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/147717"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=147709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=147709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=147709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}