{"id":14366,"date":"2015-12-08T12:03:55","date_gmt":"2015-12-08T12:03:55","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2015\/12\/08\/tienes-frio-toma-uno-quieres-ayudar-pon-uno\/"},"modified":"2015-12-08T12:03:55","modified_gmt":"2015-12-08T12:03:55","slug":"tienes-frio-toma-uno-quieres-ayudar-pon-uno","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/tienes-frio-toma-uno-quieres-ayudar-pon-uno\/","title":{"rendered":"\u00bfTienes Fr\u00edo? Toma uno&#8230;  \u00bfQuieres Ayudar? Pon uno&#8230;"},"content":{"rendered":"<p><strong>Tepeapulco<\/strong><\/p>\n<ul>\n<li><strong><strong>Ingeniosa campa\u00f1a ante la temporada invernal<\/strong><\/strong> <!--more--> <\/li>\n<\/ul>\n<p>En el exterior de la biblioteca \u2018\u2019Alfonso Reyes\u2019\u2019, de ciudad Sahag\u00fan, se lleva a cabo una ingeniosa campa\u00f1a para apoyar a la poblaci\u00f3n m\u00e1s necesitada ante la temporada invernal.<\/p>\n<p>\u00a0<\/p>\n<p>La colocaci\u00f3n de una gran cartulina con las preguntas y respuestas \u00bfTienes Fr\u00edo? Toma uno&#8230; y \u00bfQuieres Ayudar? Pon uno&#8230;<\/p>\n<p>\u00a0<\/p>\n<p>Arriba de un lazo o mecate con horquillas fue colocada para que la gente con necesidad de abrigo tome una chamarra o su\u00e9ter y que la ciudadan\u00eda que pueda\u00a0hacerlo acuda a hacer su aportaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>La idea original que es usada en el norte del pa\u00eds, se traslad\u00f3 a Ciudad Sahag\u00fan, por manos caritativas que pretenden que la poblaci\u00f3n m\u00e1s vulnerable tengan al menos un su\u00e9ter o una chamarra, para cubrirse en esta temporada invernal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tepeapulco Ingeniosa campa\u00f1a ante la temporada invernal<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-14366","post","type-post","status-publish","format-standard","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/14366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=14366"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/14366\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=14366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=14366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=14366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}