{"id":126914,"date":"2020-08-02T07:25:13","date_gmt":"2020-08-02T12:25:13","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=126914"},"modified":"2020-08-02T07:25:28","modified_gmt":"2020-08-02T12:25:28","slug":"secretaria-de-seguridad-publica-apuesta-por-una-policia-profesional","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/secretaria-de-seguridad-publica-apuesta-por-una-policia-profesional\/","title":{"rendered":"Secretar\u00eda de Seguridad P\u00fablica, apuesta por una polic\u00eda profesional"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Se dict\u00f3 conferencia magistral &#8220;Uso de Fuerza Letal y Derechos Humanos&#8221;<\/strong><\/li><\/ul>\n\n\n\n<!--more-->\n\n\n\n<p>La Secretar\u00eda de Seguridad P\u00fablica del estado de Hidalgo, mantiene el objetivo de brindar una mayor profesionalizaci\u00f3n y actualizaci\u00f3n al personal de la dependencia que comanda Mauricio Delmar Saavedra y por ello se imparti\u00f3 una conferencia magistral de manera virtual en el auditorio del Instituto de Formaci\u00f3n Profesional.<\/p>\n\n\n\n<p>En la informaci\u00f3n que se dio al respecto se aclar\u00f3 que los agentes de seguridad y cadetes del Instituto de Formaci\u00f3n Profesional de Hidalgo fueron part\u00edcipes de la conferencia magistral denominada &#8220;Uso de la Fuerza Letal y Derechos Humanos&#8221;, que fue ofrecida por el Mayor de la Polic\u00eda Nacional del Per\u00fa, Jes\u00fas Alfredo D\u00edaz Pereza.<\/p>\n\n\n\n<p>As\u00ed mismo, se reiter\u00f3 que de manera virtual, en diferentes escenarios, se sumaron el Instituto Estatal de Ciencias Penales y Seguridad P\u00fablica de Sinaloa, la Guardia Nacional y el estado de Baja California.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se dict\u00f3 conferencia magistral &#8220;Uso de Fuerza Letal y Derechos Humanos&#8221;<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-126914","post","type-post","status-publish","format-standard","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/126914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=126914"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/126914\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=126914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=126914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=126914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}