{"id":124346,"date":"2020-07-17T10:36:33","date_gmt":"2020-07-17T15:36:33","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=124346"},"modified":"2020-07-17T10:49:32","modified_gmt":"2020-07-17T15:49:32","slug":"premio-homenaje-para-winslet","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/premio-homenaje-para-winslet\/","title":{"rendered":"Premio Homenaje para Winslet"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>El festival celebrar\u00e1 su 45 edici\u00f3n del 10 al 19 de septiembre con proyecciones en varias locaciones<\/strong><\/li><\/ul>\n\n\n\n<!--more-->\n\n\n\n<p>La actriz brit\u00e1nica Kate Winslet recibir\u00e1 el Premio Homenaje del Festival Internacional de Cine de Toronto (TIFF) de este a\u00f1o en una ceremonia virtual que se celebrar\u00e1 el 15 de septiembre, durante la 45 edici\u00f3n de la muestra canadiense.<\/p>\n\n\n\n<p>TIFF, uno de los festivales de cine m\u00e1s importantes del mundo y considerado como el preferido para estrenar pel\u00edculas con opciones a los Oscar, anunci\u00f3 en junio que celebrar\u00e1 su 45 edici\u00f3n del 10 al 19 de septiembre con proyecciones en autocines, alfombras rojas virtuales y un peque\u00f1o n\u00famero de proyecciones en salas debido a la pandemia de COVID-19.<\/p>\n\n\n\n<p>El festival canadiense, que cada a\u00f1o proyecta m\u00e1s de 300 pel\u00edculas y recibe miles de periodistas, distribuidores, actores y directores de todo el mundo, tiene previsto proyectar en salas solo 50 pel\u00edculas durante los cinco primeros d\u00edas de la muestra.<\/p>\n\n\n\n<p>Los organizadores de TIFF dijeron este jueves que la entrega del Premio Homenaje a Winslet, ganadora del \u00d3scar a la mejor actriz en 2009 por &#8220;The Reader&#8221;, ser\u00e1 virtual.<\/p>\n\n\n\n<p>Es la segunda vez que TIFF entrega un Premio Homenaje, un galard\u00f3n que honra &#8220;a un actor l\u00edder en su campo por su destacada contribuci\u00f3n al cine&#8221;.<\/p>\n\n\n\n<p>El a\u00f1o pasado, que inaugur\u00f3 el premio, los ganadores fueron la actriz Meryl Streep y el actor Joaquin Phoenix.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El festival celebrar\u00e1 su 45 edici\u00f3n del 10 al 19 de septiembre con proyecciones en varias locaciones<\/p>\n","protected":false},"author":80,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-124346","post","type-post","status-publish","format-standard","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/124346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=124346"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/124346\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=124346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=124346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=124346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}