{"id":123747,"date":"2020-07-13T15:33:09","date_gmt":"2020-07-13T20:33:09","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=123747"},"modified":"2020-07-13T15:33:21","modified_gmt":"2020-07-13T20:33:21","slug":"hallan-restos-de-palacio-prehispanico-y-de-casa-de-hernan-cortes-en-mexico","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/hallan-restos-de-palacio-prehispanico-y-de-casa-de-hernan-cortes-en-mexico\/","title":{"rendered":"Hallan restos de palacio prehisp\u00e1nico y de casa de Hern\u00e1n Cort\u00e9s en M\u00e9xico"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>El hallazgo se dio en torno al patio principal del Nacional Monte de Piedad, donde se llevaban a cabo obras para reforzar las columnas que lo delimitan y soportan el primer nivel del edificio. <\/strong><\/li><\/ul>\n\n\n\n<!--more-->\n\n\n\n<p>Expertos mexicanos hallaron vestigios del palacio prehisp\u00e1nico de las Casas Viejas de Axay\u00e1catl y de los restos de una casa construida bajo las \u00f3rdenes de Hern\u00e1n Cort\u00e9s, inform\u00f3 este lunes la Secretar\u00eda de Cultura de M\u00e9xico.<\/p>\n\n\n\n<p>El hallazgo se dio en torno al patio principal del Nacional Monte de Piedad, que se ubica en pleno centro hist\u00f3rico de Ciudad de M\u00e9xico y cerca de la Catedral Metropolitana, donde se llevaban a cabo obras para reforzar las columnas que lo delimitan y soportan el primer nivel del edificio.<\/p>\n\n\n\n<p>En un comunicado, la Secretar\u00eda de Cultura indic\u00f3 que el Programa de Arqueolog\u00eda Urbana registr\u00f3 pisos de lajas de basalto, correspondientes a vestigios de un palacio prehisp\u00e1nico y de la morada del conquistador Cort\u00e9s, posterior sede del primer Cabildo de la Nueva Espa\u00f1a y del Marquesado del Valle de Oaxaca.<\/p>\n\n\n\n<p>Se apunt\u00f3 que dentro de los muros de las Casas Viejas de Axay\u00e1catl acaecieron algunos de los episodios &#8220;m\u00e1s decisivos de la conquista de M\u00e9xico-Tenochtitlan, como la muerte del tlatoani Moctezuma Xocoyotzin, posiblemente, el 29 de junio de 1520&#8221;.<\/p>\n\n\n\n<p>El bolet\u00edn se\u00f1al\u00f3 que para los arque\u00f3logos &#8220;no es ning\u00fan misterio&#8221; que bajo los pisos del Nacional Monte de Piedad, uno de los edificios m\u00e1s emblem\u00e1ticos del primer cuadro de Ciudad de M\u00e9xico, se encuentran los cimientos del Palacio de Axay\u00e1catl, el cual fue morada de la comitiva de Cort\u00e9s a su llegada al coraz\u00f3n de Tenochtitlan.<\/p>\n\n\n\n<p>EL SALVAMENTO ARQUEOL\u00d3GICO<\/p>\n\n\n\n<p>El hallazgo ocurri\u00f3 entre los primeros d\u00edas de septiembre de 2017 y hasta mediados de agosto de 2018 se estuvo realizando investigaciones, que todav\u00eda contin\u00faan.<\/p>\n\n\n\n<p>Las excavaciones dieron como resultado el hallazgo de un espacio abierto del Palacio de Axay\u00e1catl, gobernante que dirigi\u00f3 los destinos de Tenochtitlan entre 1469 y 1481, y los restos de una casa ordenada por Cort\u00e9s, del periodo virreinal temprano (1521-1620 d.C.).<\/p>\n\n\n\n<p>Los responsable de la investigaci\u00f3n explicaron que excavaron 12 pozos de sondeo -de 2 metros por lado y 1,5 metros de profundidad- en torno al patio principal del Nacional Monte de Piedad.<\/p>\n\n\n\n<p>A trav\u00e9s de los pozos, en los lados norte, este y oeste, se localizaron restos de un muro de piedra y argamasa.<\/p>\n\n\n\n<p>Tambi\u00e9n, en la secci\u00f3n oeste de este mismo espacio se encontraron los desplantes: basas y un fuste de otras columnas de la \u00e9poca virreinal temprana.<\/p>\n\n\n\n<p>Como los arque\u00f3logos tuvieron la oportunidad de realizar una excavaci\u00f3n extensiva, esta permiti\u00f3 ubicar los restos de una habitaci\u00f3n hecha con sillares de basalto y tezontle.<\/p>\n\n\n\n<p>&#8220;An\u00e1lisis posteriores permitieron concluir que \u00e9sta fue la morada de Hern\u00e1n Cort\u00e9s, una vez ca\u00edda M\u00e9xico-Tenochtitlan, en 1521&#8221;, destac\u00f3 el comunicado.<\/p>\n\n\n\n<p>Mientras que por debajo del piso firme de la casa cortesiana, a m\u00e1s de tres metros de profundidad, se detectaron los restos de otro piso de lajas de basalto, pero de \u00e9poca prehisp\u00e1nica.<\/p>\n\n\n\n<p>Dadas las caracter\u00edsticas, los expertos sostienen que form\u00f3 parte de un espacio abierto del antiguo Palacio de Axay\u00e1catl, probablemente, un patio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hallazgo se dio en torno al patio principal del Nacional Monte de Piedad, donde se llevaban a cabo obras para reforzar las columnas que lo delimitan y soportan el primer nivel del edificio.<\/p>\n","protected":false},"author":80,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-123747","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/123747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=123747"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/123747\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=123747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=123747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=123747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}