{"id":123554,"date":"2020-07-13T06:00:00","date_gmt":"2020-07-13T11:00:00","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=123554"},"modified":"2020-07-12T22:16:57","modified_gmt":"2020-07-13T03:16:57","slug":"aduanas-decomisa-165-kilogramos-de-cocaina-en-lazaro-cardenas-michoacan","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/aduanas-decomisa-165-kilogramos-de-cocaina-en-lazaro-cardenas-michoacan\/","title":{"rendered":"Aduanas decomisa 165 kilogramos de coca\u00edna, en L\u00e1zaro C\u00e1rdenas, Michoac\u00e1n"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>La carga se puso a disposici\u00f3n de la FGR, para su investigaci\u00f3n\u00a0<\/strong><\/li><\/ul>\n\n\n\n<!--more-->\n\n\n\n<p>La Administraci\u00f3n General de Aduanas (AGA), a cargo de Horacio Duarte Olivares, decomis\u00f3 164.98 kilogramos de coca\u00edna en la aduana de L\u00e1zaro C\u00e1rdenas, Michoac\u00e1n, en un buque carguero proveniente de Buenaventura, Colombia.<\/p>\n\n\n\n<p>Los trabajos de inteligencia y de coordinaci\u00f3n con autoridades federales y de Estados Unidos, permitieron monitorear la embarcaci\u00f3n desde su salida del puerto colombiano.<\/p>\n\n\n\n<p>El personal de la aduana de L\u00e1zaro C\u00e1rdenas solicit\u00f3 la colaboraci\u00f3n de la Marina Armada de M\u00e9xico y de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para realizar la b\u00fasqueda en el embarque de carb\u00f3n donde fueron localizadas maletas negras con 140 paquetes ocultos. La carga se puso a disposici\u00f3n de la FGR para iniciar la carpeta de investigaci\u00f3n correspondiente.<\/p>\n\n\n\n<p>Con estas acciones, se cumple con el ABC institucional que tiene como objetivo: aumentar la recaudaci\u00f3n y combatir la corrupci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carga se puso a disposici\u00f3n de la FGR, para su investigaci\u00f3n\u00a0<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-123554","post","type-post","status-publish","format-standard","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/123554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=123554"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/123554\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=123554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=123554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=123554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}