{"id":112251,"date":"2020-05-28T06:00:00","date_gmt":"2020-05-28T11:00:00","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=112251"},"modified":"2020-05-27T22:03:24","modified_gmt":"2020-05-28T03:03:24","slug":"transportaba-mil-600-litros-de-huachicol-detenido","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/transportaba-mil-600-litros-de-huachicol-detenido\/","title":{"rendered":"Transportaba mil 600 litros de huachicol; detenido"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Intent\u00f3 huir de los elementos policiacos, cuando transitaba por la colonia Guadalupe<\/strong><\/li><\/ul>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Un sujeto que conduc\u00eda una camioneta tipo Van, fue detenido por elementos de&nbsp; Seguridad P\u00fablica de Tulancingo por su presunta participaci\u00f3n en el trasiego de hidrocarburo de dudosa procedencia, el pasado martes, en la colonia Guadalupe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autoridades policiales informaron que elementos de seguridad p\u00fablica realizaban recorridos habituales de inspecci\u00f3n sobre la calle 16 de Septiembre y Tl\u00e1loc, en la colonia Guadalupe, cuando se percataron que una camioneta GMC Safari, transitaba con evidente exceso de carga, sin embargo, el conductor de la camioneta al ver la presencia policial aceler\u00f3 su unidad en vano intento de huida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los oficiales iniciaron una persecuci\u00f3n y en la esquina de las calles Tolteca y Uxmal, el individuo descendi\u00f3 de la unidad vehicular para intentar escapar a pie, pero fue alcanzado metros adelante por los agentes policiacos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al inspeccionar la camioneta, fueron localizados en su interior ocho tambos con capacidad de 200 litros cada uno, todos abastecidos con combustible al 100 por ciento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al no comprobar el origen legal del hidrocarburo, el conductor, que se identific\u00f3 con el nombre cuyas iniciales son AFR, de 35 a\u00f1os de edad, fue detenido; mientras que la camioneta fue asegurada junto con los mil 600 litros de gasolina, que fueron puestos a disposici\u00f3n de las autoridades competentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intent\u00f3 huir de los elementos policiacos, cuando transitaba por la colonia Guadalupe<\/p>\n","protected":false},"author":70,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-112251","post","type-post","status-publish","format-standard","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/112251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=112251"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/112251\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=112251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=112251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=112251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}