{"id":109472,"date":"2020-05-13T00:02:34","date_gmt":"2020-05-13T00:02:34","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=109472"},"modified":"2020-05-13T00:41:32","modified_gmt":"2020-05-13T00:41:32","slug":"en-vivo-conferencia-de-prensa-sobre-covid-19-10","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/en-vivo-conferencia-de-prensa-sobre-covid-19-10\/","title":{"rendered":"Suman 3 mil 926 muertes por Covid-19 en M\u00e9xico; hay 38,324 casos"},"content":{"rendered":"\n<p><strong>Hay 22 mil 980 casos sospechosos, aunque con 80 mil 900 casos negativos acumulados en el pa\u00eds.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>M\u00e9xico lleg\u00f3, al corte de este 12 de mayo, a 3 mil 926\u00a0 muertes por Covid-19, con 38 mil 324 casos de contagios confirmados de coronavirus, seg\u00fan informaron autoridades de la\u00a0Secretar\u00eda de Salud.\u00a0<\/p>\n\n\n\n<p>Jos\u00e9 Luis Alom\u00eda, director general de Epidemiolog\u00eda, detall\u00f3 que hay 22 mil 980 casos sospechosos, aunque con 80 mil 900 casos negativos acumulados en el pa\u00eds.<\/p>\n\n\n\n<p>Hasta este lunes, la Secretar\u00eda de Salud hab\u00eda confirmado 36 mil 327 contagios, 3 mil 573 muertos y m\u00e1s de 8 mil casos activos por Covid-19 en M\u00e9xico.<\/p>\n\n\n\n<p>La tarde de este martes, el gobierno federal present\u00f3 el plan &#8220;de regreso a nueva normalidad&#8221; a los gobernadores del pa\u00eds, a trav\u00e9s de una reuni\u00f3n virtual. En la estrategia se plante\u00f3 que el regreso a las actividades ser\u00e1 gradual y deber\u00e1 conservarse la sana distancia para evitar un rebrote por este virus.\u00a0<\/p>\n\n\n\n<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador anticip\u00f3 en su conferencia de prensa matutina que dicho plan ser\u00e1 difundido a partir de este mi\u00e9rcoles a la poblaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed-facebook wp-block-embed is-type-video is-provider-facebook\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.facebook.com\/SecretariadeSaludMX\/videos\/1536544196547764\/\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hay 22 mil 980 casos sospechosos, aunque con 80 mil 900 casos negativos acumulados en el pa\u00eds.<\/p>\n","protected":false},"author":81,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36],"tags":[],"class_list":["post-109472","post","type-post","status-publish","format-standard","hentry","category-destacadas","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/109472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=109472"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/109472\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=109472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=109472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=109472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}