{"id":107461,"date":"2020-05-03T06:00:00","date_gmt":"2020-05-03T06:00:00","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=107461"},"modified":"2020-05-03T03:18:59","modified_gmt":"2020-05-03T03:18:59","slug":"luchadores-combaten-el-tedio-de-la-pandemia-con-ejercicios-en-casa","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/luchadores-combaten-el-tedio-de-la-pandemia-con-ejercicios-en-casa\/","title":{"rendered":"Luchadores &#8220;combaten&#8221; el tedio de la pandemia con ejercicios en casa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El reconocido gladiador S\u00faper Mu\u00f1eco, con 38 a\u00f1os como profesional, se coloca la m\u00e1scara y ropa c\u00f3moda para comenzar una serie de ejercicios<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Con la pausa obligada por la pandemia del Covid-19, los populares luchadores mexicanos han guardado sus coloridos atuendos y m\u00e1scaras para refugiarse en sus casas y ejercitarse como pueden con la esperanza de volver pronto al cuadril\u00e1tero.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el interior de un peque\u00f1o departamento en la popular zona de la Merced, en el centro de la Ciudad de M\u00e9xico, la magia de la lucha libre, ese deporte-espect\u00e1culo altamente consumido en este pa\u00eds, se percibe por doquier.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reconocido gladiador S\u00faper Mu\u00f1eco, con 38 a\u00f1os como profesional, se coloca la m\u00e1scara y ropa c\u00f3moda para comenzar una serie de ejercicios con los que se mantiene activo f\u00edsicamente durante la cuarentena que ha confinado en sus casas a millones de personas en el mundo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque falta el cuadril\u00e1tero, con su 12 cuerdas y 36 metros cuadrados de lona, los luchadores mexicanos se las ingenian para &#8220;entrenar en casa&#8221; como lo hace S\u00faper Mu\u00f1eco.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acostumbrado a la actividad constante, tanto en el entrenamiento como en los combates, el gladiador mexicano al igual que cientos de sus colegas se encuentra ca\u00eddo en la lona por ese &#8220;rudo rival&#8221; llamado coronavirus que suma m\u00e1s de 3 millones de contagios a nivel mundial y se ha cobrado la vida de m\u00e1s de 200 mil personas&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Podr\u00e1n desaparecer los luchadores, pero la lucha libre no va desaparecer nunca&#8221;, cont\u00f3 en entrevista con Efe el popular luchador S\u00faper Mu\u00f1eco.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan su experiencia en sus viajes al extranjero, a los mexicanos les identifican con las palabras &#8220;mariachis, tequila y m\u00e1scaras&#8221;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el gladiador, cuya m\u00e1scara tiene como personaje a un sonriente payaso, el confinamiento ha sido una medida dura.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Es dif\u00edcil estar encerrado&#8221; y aunque ha evitado salir &#8220;por miedo a la pandemia y&nbsp; morir&#8221;, cuando ha dejado su casa para comprar comida y alimentos, lo ha hecho con total precauci\u00f3n.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocido gladiador S\u00faper Mu\u00f1eco, con 38 a\u00f1os como profesional, se coloca la m\u00e1scara y ropa c\u00f3moda para comenzar una serie de ejercicios<\/p>\n","protected":false},"author":80,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-107461","post","type-post","status-publish","format-standard","hentry","category-deportiva"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/107461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=107461"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/107461\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=107461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=107461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=107461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}