{"id":102375,"date":"2020-04-07T18:16:30","date_gmt":"2020-04-07T18:16:30","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2020\/04\/07\/hallaron-tres-cadaveres-en-nopala\/"},"modified":"2020-04-16T16:50:52","modified_gmt":"2020-04-16T16:50:52","slug":"hallaron-tres-cadaveres-en-nopala","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/hallaron-tres-cadaveres-en-nopala\/","title":{"rendered":"Hallaron tres cad\u00e1veres en Nopala"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La informaci\u00f3n oficial establece que fue esta ma\u00f1ana al filo de las 08:00 horas, cuando se dio la alerta al 911 de Emergencias <\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Vecinos del municipio de Nopala de Villagran, reportaron sobre el hallazgo de tres cuerpos sin vida y de inmediato se gener\u00f3 una intensa movilizaci\u00f3n policial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n oficial establece que fue esta ma\u00f1ana al filo de las 08:00 horas, cuando se dio la alerta al 911 de Emergencias, por lo que v\u00eda radio se hizo extensiva a las corporaciones polic\u00edacas de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El macabro hallazgo tuvo lugar a la orilla de la Carretera estatal Nopala-Polotitl\u00e1n, en las inmediaciones de la localidad de El Fresno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sl acudir al lugar elementos de la Agencia de Seguridad Estatal corroboraron la veracidad del reporte, en tanto que agentes de la Polic\u00eda Municipal de Nopala notificaron de la localizaci\u00f3n de tres personas sin signos de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para preservar la escena del hallazgo, los guardianes de la ley decidieron acordonar el sitio y resguardarlo en espera de personal de la Procuradur\u00eda General de Justicia de Hidalgo para llevar a cabo las diligencias correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La informaci\u00f3n oficial establece que fue esta ma\u00f1ana al filo de las 08:00 horas, cuando se dio la alerta al 911 de Emergencias<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-102375","post","type-post","status-publish","format-standard","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/102375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=102375"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/102375\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=102375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=102375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=102375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}